{"id":94929,"date":"2022-10-04T12:43:59","date_gmt":"2022-10-04T12:43:59","guid":{"rendered":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1.png"},"modified":"2022-10-04T12:44:58","modified_gmt":"2022-10-04T12:44:58","slug":"94926_1-2","status":"inherit","type":"attachment","link":"https:\/\/yogaesoteric.net\/en\/94926_1-2\/","title":{"rendered":"94926_1"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"class_list":["post-94929","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-e1664887457115.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"211\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-300x211.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-300x211.png 300w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-768x539.png 768w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1.png 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Le site de la centrale de Zaporodje est situ\u00e9 \u00e0 55 km en aval, \u00e0 Energodar<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":1024,"height":719,"file":"2022\/10\/94926_1.png","filesize":1564283,"sizes":{"medium":{"file":"94926_1-300x211.png","width":300,"height":211,"filesize":141092,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-300x211.png"},"thumbnail":{"file":"94926_1-150x150.png","width":150,"height":150,"filesize":53673,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-150x150.png"},"medium_large":{"file":"94926_1-768x539.png","width":768,"height":539,"filesize":751203,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-768x539.png"},"publisher-tb1":{"file":"94926_1-86x64.png","width":86,"height":64,"filesize":13764,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-86x64.png"},"publisher-sm":{"file":"94926_1-210x136.png","width":210,"height":136,"filesize":67506,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-210x136.png"},"publisher-mg2":{"file":"94926_1-279x220.png","width":279,"height":220,"filesize":137918,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-279x220.png"},"publisher-md":{"file":"94926_1-357x210.png","width":357,"height":210,"filesize":168558,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-357x210.png"},"publisher-lg":{"file":"94926_1-750x430.png","width":750,"height":430,"filesize":620015,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-750x430.png"},"publisher-full":{"file":"94926_1-1024x580.png","width":1024,"height":580,"filesize":1061458,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-1024x580.png"},"publisher-tall-sm":{"file":"94926_1-180x217.png","width":180,"height":217,"filesize":90371,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-180x217.png"},"publisher-tall-lg":{"file":"94926_1-267x322.png","width":267,"height":322,"filesize":187506,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-267x322.png"},"publisher-tall-big":{"file":"94926_1-368x445.png","width":368,"height":445,"filesize":332994,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-368x445.png"},"full":{"file":"94926_1-e1664887457115.png","width":1024,"height":719,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-e1664887457115.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_1-e1664887457115.png","_links":{"self":[{"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/media\/94929","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/comments?post=94929"}]}}