{"id":94932,"date":"2022-10-04T12:44:03","date_gmt":"2022-10-04T12:44:03","guid":{"rendered":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2.png"},"modified":"2022-10-04T12:45:51","modified_gmt":"2022-10-04T12:45:51","slug":"94926_2-2","status":"inherit","type":"attachment","link":"https:\/\/yogaesoteric.net\/en\/94926_2-2\/","title":{"rendered":"94926_2"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false},"class_list":["post-94932","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-e1664887546895.png'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"175\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-300x175.png\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-300x175.png 300w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-768x448.png 768w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-357x210.png 357w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2.png 941w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Attaque ukrainienne contre la centrale nucl\u00e9aire d\u2019Energodar le 20 juillet<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":941,"height":549,"file":"2022\/10\/94926_2.png","filesize":797923,"sizes":{"medium":{"file":"94926_2-300x175.png","width":300,"height":175,"filesize":89598,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-300x175.png"},"thumbnail":{"file":"94926_2-150x150.png","width":150,"height":150,"filesize":40534,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-150x150.png"},"medium_large":{"file":"94926_2-768x448.png","width":768,"height":448,"filesize":432542,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-768x448.png"},"publisher-tb1":{"file":"94926_2-86x64.png","width":86,"height":64,"filesize":12146,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-86x64.png"},"publisher-sm":{"file":"94926_2-210x136.png","width":210,"height":136,"filesize":52483,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-210x136.png"},"publisher-mg2":{"file":"94926_2-279x220.png","width":279,"height":220,"filesize":98091,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-279x220.png"},"publisher-md":{"file":"94926_2-357x210.png","width":357,"height":210,"filesize":122251,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-357x210.png"},"publisher-lg":{"file":"94926_2-750x430.png","width":750,"height":430,"filesize":410328,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-750x430.png"},"publisher-tall-sm":{"file":"94926_2-180x217.png","width":180,"height":217,"filesize":64659,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-180x217.png"},"publisher-tall-lg":{"file":"94926_2-267x322.png","width":267,"height":322,"filesize":124465,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-267x322.png"},"publisher-tall-big":{"file":"94926_2-368x445.png","width":368,"height":445,"filesize":209641,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-368x445.png"},"full":{"file":"94926_2-e1664887546895.png","width":941,"height":549,"mime_type":"image\/png","source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-e1664887546895.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2022\/10\/94926_2-e1664887546895.png","_links":{"self":[{"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/media\/94932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/en\/wp-json\/wp\/v2\/comments?post=94932"}]}}