{"id":12116,"date":"2018-07-17T14:26:23","date_gmt":"2018-07-17T14:26:23","guid":{"rendered":"http:\/\/dev.yogaesoteric.net\/actualite-fr\/societe-1602-fr\/archives-3495-fr\/les-merveilleuses-proprietes-curatives-du-celeri\/"},"modified":"2018-07-17T14:26:23","modified_gmt":"2018-07-17T14:26:23","slug":"les-merveilleuses-proprietes-curatives-du-celeri","status":"publish","type":"post","link":"https:\/\/yogaesoteric.net\/fr\/les-merveilleuses-proprietes-curatives-du-celeri\/","title":{"rendered":"Les merveilleuses propri\u00e9t\u00e9s curatives du c\u00e9leri"},"content":{"rendered":"<p align=\"justify\">&#160;<\/p>\n<p align=\"justify\">La consommation r&#233;guli&#232;re de c&#233;leri nous aide &#224; r&#233;guler le taux de cholest&#233;rol dans le sang, &#224; &#233;liminer l&#8217;acide urique, &#224; pr&#233;venir les affections cardiaques, ainsi qu&#8217;&#224; combattre l&#8217;hypertension et les douleurs menstruelles.<\/p>\n<p align=\"justify\">\n<p>    <img loading=\"lazy\" decoding=\"async\" border=\"0\" hspace=\"5\" alt=\"\" vspace=\"5\" src=\"\/all_uploads\/uploads-dec17\/mai\/9\/15707\/15707_1.jpg\" width=\"500\" height=\"254\" \/><\/p>\n<p align=\"justify\">Le c&#233;leri, le persil et le fenouil sont des plantes de la famille des ombellif&#232;res. Depuis des si&#232;cles, les propri&#233;t&#233;s curatives du c&#233;leri sont utilis&#233;es comme ingr&#233;dient de base de la m&#233;decine naturelle dans diverses cultures ; de ce fait, sa consommation s&#8217;est beaucoup &#233;tendue et il constitue l&#8217;ingr&#233;dient principal de nombreuses formules m&#233;dicinales actuelles.<\/p>\n<p align=\"justify\">Voici une liste de certains des bienfaits de cette plante pour la sant&#233; :<br \/>&#8211; Il s&#8217;agit d&#8217;une plante qui a d&#8217;int&#233;ressantes propri&#233;t&#233;s nutritives par sa teneur en vitamines A, B, E et C. De plus, elle contient des min&#233;raux indispensables &#224; un bon fonctionnement de l&#8217;organisme tels que le fer, le potassium, le zinc, le phosphore, le soufre, le cuivre, l&#8217;aluminium et le mangan&#232;se.<br \/>&#8211; Prendre une infusion de c&#233;leri chaque jour est un bon moyen pour pr&#233;venir l&#8217;hypertension, les douleurs menstruelles ou faire baisser un taux &#233;lev&#233; de cholest&#233;rol. Consomm&#233; ti&#232;de et avec constance, il soigne l&#8217;aphonie ou l&#8217;extinction de voix.<br \/>&#8211; Les graines de c&#233;leri contiennent des huiles essentielles (limon&#232;ne et s&#233;lin&#232;ne) et sa racine de l&#8217;asparagine. Ces composants exercent une intense action d&#233;purative et diur&#233;tique. Ces huiles donnent lieu &#224; un processus de dilatation des vaisseaux r&#233;naux qui permet &#224; l&#8217;organisme d&#8217;&#233;liminer les impuret&#233;s et l&#8217;exc&#233;dent de liquide, favorisant ainsi un bon &#233;quilibre des fonctions vitales.<br \/>&#8211; Il est tr&#232;s efficace dans le traitement des calculs biliaires et r&#233;naux en favorisant l&#8217;&#233;limination naturelle des gravelles, de m&#234;me que dans le traitement des affections h&#233;patiques.<br \/>&#8211; Il peut &#234;tre tr&#232;s utile pour soigner les troubles circulatoires, car sa consommation r&#233;guli&#232;re fait baisser le taux de cholest&#233;rol dans le sang et sert &#224; &#233;liminer un surplus d&#8217;acide urique ; il aide &#233;galement &#224; pr&#233;venir les probl&#232;mes cardiaques et &#224; combattre l&#8217;hypertension.<br \/>&#8211; Le c&#233;leri est recommand&#233; dans le traitement des probl&#232;mes articulaires pour sa teneur en flavono&#239;des. Les flavono&#239;des exercent une action anti-inflammatoire et antioxydante, et ils renforcent le syst&#232;me immunitaire. De plus il renferme du silice qui stimule la production et le renouvellement des tissus articulaire et conjonctif.<br \/>&#8211; Il soulage les inflammations provoqu&#233;es par la goutte, le rhumatisme ou l&#8217;arthrite, car il contribue &#224; &#233;liminer l&#8217;acide urique, comme on l&#8217;a mentionn&#233; plus haut, principale cause de ces maux.<br \/>&#8211; Le c&#233;leri s&#233;ch&#233; et moulu sert &#224; soigner les petites plaies de la bouche et les probl&#232;mes de gencives. Il suffit de l&#8217;utiliser en bains de bouche deux &#224; trois fois par semaine.<br \/>&#8211; Pour stimuler l&#8217;app&#233;tit des plus petits, pr&#233;parer un bouillon &#224; raison d&#8217;une poign&#233;e de c&#233;leri par litre d&#8217;eau, et leur faire boire avant les repas.<br \/>&#8211; Utilis&#233; comme ingr&#233;dient dans les principaux plats et en salades, sa consommation aide &#224; renforcer, &#224; r&#233;guler et &#224; garder un intestin en bonne sant&#233;, en facilitant ainsi la digestion et en &#233;vitant les probl&#232;mes de constipation.<br \/>&#8211; Les jus ou les concentr&#233;s de c&#233;leri ont deux propri&#233;t&#233;s particuli&#232;res reconnues dans le monde entier : calmante et aphrodisiaque. Boire un verre de jus de c&#233;leri tous les jours a un effet tranquilisant et anti-stress, et permet de stimuler le d&#233;sir sexuel lors d&#8217;une baisse de la libido.<br \/>&#8211; Les cataplasmes de c&#233;leri (le v&#233;g&#233;tal r&#233;duit en pur&#233;e auquel on ajoute un peu d&#8217;eau) sont tr&#232;s cicatrisants et d&#233;sinfectants pour les blessures et les plaies ouvertes sur lesquelles il faudra les appliquer trois fois par jour durant environ quinze minutes.<\/p>\n<p align=\"justify\">D&#232;s lors, vous savez que l&#8217;apport de cette plante dans votre alimentation journali&#232;re aura de grands avantages pour votre sant&#233; et celle de votre famille. Gr&#226;ce au c&#233;leri, il vous sera possible dor&#233;navant de soigner bien des maux avec un produit naturel et organique sans avoir recours &#224; des produits chimiques.<\/p>\n<p align=\"justify\">N&#8217;h&#233;sitez pas &#224; utiliser le c&#233;leri de mani&#232;re quotidienne, dans votre alimentation ou comme base dans les diff&#233;rentes pr&#233;parations qu&#8217;on a pr&#233;sent&#233;es !<\/p>\n<p align=\"justify\">\n    <strong>Les bienfaits sant&#233; du c&#233;leri<\/strong>\n  <\/p>\n<p align=\"justify\">\n<p>    <img loading=\"lazy\" decoding=\"async\" style=\"border-top-color: ; border-left-color: ; border-bottom-color: ; border-right-color: \" border=\"0\" hspace=\"5\" alt=\"\" vspace=\"5\" src=\"\/all_uploads\/uploads4\/iulie\/17\/15707\/15707_2.jpg\" width=\"500\" height=\"331\" \/><\/p>\n<p align=\"justify\">Qu&#8217;il soit rave ou en branche, le c&#233;leri ne manque pas d&#8217;atouts nutritionnels. Reconnu comme &#233;tant diur&#233;tique, il est aussi l&#8217;un des aliments les moins caloriques qui soient. Autre atout : sa richesse en antioxydants. <\/p>\n<p align=\"justify\">Fort en go&#251;t, le c&#233;leri permet de multiples d&#233;clinaisons en cuisine. Il peut s&#8217;associer &#224; de nombreux autres l&#233;gumes. On aurait tort de s&#8217;en priver, car il rec&#232;le plein de bienfaits sant&#233;. <\/p>\n<p align=\"justify\">\n    <strong>Un l&#233;gume coupe-faim<\/strong>\n  <\/p>\n<p align=\"justify\">Le c&#233;leri-rave est moins calorique que les haricots verts, &#224; condition de ne pas le manger &#224; la r&#233;moulade&#8201;! En outre, il fournit des fibres qui aident &#224; se sentir rapidement et longtemps rassasi&#233;. Le temps qu&#8217;il faut pour bien le m&#226;cher favorise aussi une bonne sati&#233;t&#233;. <\/p>\n<p align=\"justify\">\n    <strong>Un aliment anti-&#226;ge<\/strong>\n  <\/p>\n<p align=\"justify\">Le c&#233;leri renferme plusieurs antioxydants : de la lut&#233;ine, du b&#234;tacarot&#232;ne, des flavono&#239;des&#8230; Ces antioxydants ont diverses propri&#233;t&#233;s : certains sont anti-inflammatoires, d&#8217;autres sont b&#233;n&#233;fiques &#224; la sant&#233; des yeux ou de la peau&#8230; En consommer permet d&#8217;aider l&#8217;organisme &#224; se prot&#233;ger des radicaux libres pouvant endommager les cellules de l&#8217;organisme. <\/p>\n<p align=\"justify\">\n    <strong>Le c&#233;leri est diur&#233;tique<\/strong>\n  <\/p>\n<p align=\"justify\">Le c&#233;leri apporte entre 15 et 18\u202f% des besoins quotidiens en potassium. Ce min&#233;ral favorise l&#8217;&#233;limination des toxines par les reins, il limite &#233;galement la r&#233;tention d&#8217;eau et donc la formation de cellulite. <\/p>\n<p align=\"justify\">\n    <strong>Une bonne source de folates<\/strong>\n  <\/p>\n<p align=\"justify\">Le c&#233;leri-rave est une bonne source de folates (vitamine B9) indispensables lors de la grossesse, mais aussi d&#232;s le d&#233;sir d&#8217;enfant, afin de limiter les risques d&#8217;anomalies du placenta et, surtout, de spina-bifida chez le futur b&#233;b&#233;. Il en apporte 15\u202f% des valeurs nutritionnelles recommand&#233;es. Les enfants ont aussi besoin de folates en raison de leur croissance rapide les premi&#232;res ann&#233;es. <\/p>\n<p align=\"justify\">\n    <strong>Rave ou en branche, quelles diff&#233;rences&#8201;nutritionnelles <\/strong>\n  <\/p>\n<p align=\"justify\">Le c&#233;leri-rave et le c&#233;leri branche, sont deux vari&#233;t&#233;s diff&#233;rentes de la m&#234;me plante. <br \/>&#8211; Le c&#233;leri branche est encore moins calorique que le c&#233;leri-rave\u202f: 21 calories aux 100\u202fg contre 32. Il est plus riche en eau (93,5\u202f% contre 88) et en calcium (48\u202fmg aux 100\u202fg contre 34\u202fmg). <br \/>&#8211; Le c&#233;leri-rave fournit davantage de potassium\u202f: 377\u202fmg aux 100\u202fg contre 289\u202fmg et plus de deux fois plus de fibres\u202f: 3,7\u202fg contre 1,7\u202fg. <\/p>\n<p align=\"justify\">\n    <strong>Pr&#233;cautions sant&#233; avant de consommer du c&#233;leri<\/strong>\n  <\/p>\n<p align=\"justify\">Vous avez un terrain allergique : les personnes allergiques au pollen de bouleau ou d&#8217;armoise peuvent &#233;galement &#234;tre intol&#233;rantes au c&#233;leri. Ce l&#233;gume de la famille des ombellif&#232;res arrive en troisi&#232;me position des allerg&#232;nes alimentaires chez l&#8217;adulte. L&#8217;allergie au c&#233;leri se rencontre aussi chez les personnes allergiques au soja.<\/p>\n<p align=\"justify\">\n<p>    <img loading=\"lazy\" decoding=\"async\" style=\"border-top-color: ; border-left-color: ; border-bottom-color: ; border-right-color: \" border=\"0\" hspace=\"5\" alt=\"\" vspace=\"5\" src=\"\/all_uploads\/uploads4\/iulie\/17\/15707\/15707_3.jpg\" width=\"500\" height=\"290\" \/><\/p>\n<p align=\"justify\">Vous travaillez dehors : le c&#233;leri branche contient des psoral&#232;nes qui sont photosensibles. Une exposition &#224; la lumi&#232;re ou aux UV artificiels apr&#232;s la consommation de c&#233;leri peut donc entra&#238;ner une &#233;ruption cutan&#233;e avec rougeurs, v&#233;sicules, voire des cloques. <\/p>\n<p align=\"justify\">\n    <strong>Acheter, conserver et cuisiner le c&#233;leri<\/strong>\n  <\/p>\n<p align=\"justify\">Achat du c&#233;leri : le choisir plut&#244;t bio car il fait partie des douze fruits et l&#233;gumes les plus contamin&#233;s par les pesticides (source : &#233;tude Environmental Working Group 2015). Pour le c&#233;leri-rave, optez pour une petite boule, car si elle fait plus de 10 \u202fcm de diam&#232;tre ou plus d&#8217;un kilo, elle risque d&#8217;&#234;tre creuse. Pour le c&#233;leri-branche, pr&#233;f&#233;rez-le avec les feuilles vertes et les branches fermes. <\/p>\n<p align=\"justify\">Conservation du c&#233;leri : une dizaine de jours dans le bac &#224; l&#233;gumes du r&#233;frig&#233;rateur pour le c&#233;leri-rave, quelques jours dans un linge humide pour celui en branche. <\/p>\n<p align=\"justify\">\n    <strong>Pr&#233;paration du c&#233;leri :<\/strong>\n  <\/p>\n<p align=\"justify\">Le c&#233;leri-rave s&#8217;&#233;pluche au couteau &#233;conome. Le citronner pour &#233;viter qu&#8217;il noircisse. Il se coupe en d&#233;s pour &#234;tre cuit et mix&#233; en pur&#233;e, ou il se r&#226;pe cru pour &#234;tre consomm&#233; en salade. <\/p>\n<p align=\"justify\">Le c&#233;leri-branche s&#8217;&#233;pluche au couteau &#233;conome pour retirer les fils. Cru, les tiges se d&#233;gustent en salade ou en amuse-bouche. Cuit, c&#244;tes et feuilles parfument les soupes, ou s&#8217;ajoutent aux l&#233;gumes.<\/p>\n<p align=\"justify\">&#160;<\/p>\n<p align=\"justify\">\n    <strong>yogaesoteric<br \/>17 juillet 2018<br \/><\/strong>\n  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#160; La consommation r&#233;guli&#232;re de c&#233;leri nous aide &#224; r&#233;guler le taux de cholest&#233;rol dans le sang, &#224; &#233;liminer l&#8217;acide urique, &#224; pr&#233;venir les affections cardiaques, ainsi qu&#8217;&#224; combattre l&#8217;hypertension et les douleurs menstruelles. Le c&#233;leri, le persil et le fenouil sont des plantes de la famille des ombellif&#232;res. Depuis des si&#232;cles, les propri&#233;t&#233;s curatives [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1303],"tags":[],"class_list":["post-12116","post","type-post","status-publish","format-standard","hentry","category-archives-3495-fr"],"_links":{"self":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/12116","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/comments?post=12116"}],"version-history":[{"count":0,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/12116\/revisions"}],"wp:attachment":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/media?parent=12116"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/categories?post=12116"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/tags?post=12116"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}