{"id":15243,"date":"2019-11-18T18:06:27","date_gmt":"2019-11-18T18:06:27","guid":{"rendered":"http:\/\/dev.yogaesoteric.net\/demasquer-la-maconnerie-fr\/la-franc-maconnerie-en-roumanie-3480-fr\/laustralie-dit-non-pour-la-2eme-fois\/"},"modified":"2019-11-18T18:06:27","modified_gmt":"2019-11-18T18:06:27","slug":"laustralie-dit-non-pour-la-2eme-fois","status":"publish","type":"post","link":"https:\/\/yogaesoteric.net\/fr\/laustralie-dit-non-pour-la-2eme-fois\/","title":{"rendered":"L\u2019Australie dit non pour la 2\u00e8me fois !"},"content":{"rendered":"<p align=\"justify\">\n    \n  <\/p>\n<p align=\"justify\">\n    <strong>Julia Gillard, ancien Premier Ministre Australien<\/strong>\n  <\/p>\n<p align=\"justify\">Les musulmans qui veulent vivre sous la charia islamique ont &#233;t&#233; pri&#233;s de quitter l&#8217;Australie ! Le gouvernement a cibl&#233; les radicaux dans le but de parer les attaques terroristes potentielles. Par ailleurs, Mme Gillard a irrit&#233; certains musulmans australiens en d&#233;clarant en 2011 qu&#8217;elle soutenait les agences d&#8217;espionnage qui surveillent les mosqu&#233;es pr&#233;sentes sur le sol de la nation. <\/p>\n<p align=\"center\">\n    <img decoding=\"async\" alt=\"\" src=\"\/all_uploads\/uploads5\/noiembrie%202019\/13\/21396_1.jpg\" \/>&#160;<\/p>\n<p align=\"justify\">\n    <strong><br \/>\n      <u><br \/>\n      <\/u><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"justify\">\n    <strong>Citation :<\/strong>\n  <\/p>\n<p align=\"justify\">&#171; Les immigrants, doivent s&#8217;adapter. C&#8217;est &#224; prendre ou &#224; laisser. Je suis fatigu&#233;e que cette nation s&#8217;inqui&#232;te de savoir si nous offensons certains individus ou leur culture. Notre culture s&#8217;est d&#233;velopp&#233;e depuis plus de deux si&#232;cles, apr&#232;s tant de luttes, d&#8217;&#233;preuves et de victoires par des millions d&#8217;hommes et de femmes qui ont recherch&#233; la libert&#233;. <\/p>\n<p align=\"justify\">\n<p align=\"justify\">\n    Nous parlons l&#8217;anglais et non pas l&#8217;espagnol, le libanais, l&#8217;arabe, le chinois, le japonais, le russe ou autre langage.\n  <\/p>\n<p align=\"justify\">\n    Donc, si vous voulez faire partie de notre soci&#233;t&#233;, apprenez notre langue ! La plupart des australiens croient en Dieu. Il n&#8217;est pas question ici de &#8220; droit chr&#233;tien &#8221; ou une quelconque pression politique, c&#8217;est un FAIT parce que les chr&#233;tiens hommes et femmes, avec leurs principes Chr&#233;tiens ont fond&#233;s cette nation.\n  <\/p>\n<p align=\"justify\">\n<p align=\"justify\">\n    Il est parfaitement appropri&#233; de les afficher sur les murs de nos &#233;coles ! Dieu vous offense, je vous sugg&#232;re alors d&#8217;envisager une autre partie du monde pour y vivre, car Dieu fait partie de notre culture.\n  <\/p>\n<p align=\"justify\">\n<p align=\"justify\">\n    Tout ce que nous vous demandons, c&#8217;est de respecter les n&#244;tres, de vivre pacifiquement et en harmonie avec nous. Ceci est notre pays, notre terre, et notre style de vie et nous vous donnons l&#8217;occasion d&#8217;en profiter. Mais &#224; partir du moment o&#249; vous vous mettez &#224; vous plaindre, &#224; g&#233;mir et &#224; ronchonner &#224; propos de notre drapeau, notre engagement, nos croyances chr&#233;tiennes ou notre style de vie, je vous encourage fortement &#224; profiter d&#8217;une autre grande libert&#233; Australienne : &#8220; le droit de partir &#8221;.\n  <\/p>\n<p align=\"justify\">\n<p>    Si vous n&#8217;&#234;tes pas heureux ici et bien partez ! Nous ne vous avons pas forc&#233; &#224; venir ! Vous &#234;tes venus tout seul alors acceptez le pays qui vous a accept&#233;, tel qu&#8217;il est ! &#187; <br \/>\n  &#160;<br \/>\n  &#160;<\/p>\n<p>    <strong><br \/>\n      <br \/>yogaesoteric<\/strong><br \/>\n    <br \/>\n    <strong>18 novembre 2019<\/strong><\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Julia Gillard, ancien Premier Ministre Australien Les musulmans qui veulent vivre sous la charia islamique ont &#233;t&#233; pri&#233;s de quitter l&#8217;Australie ! Le gouvernement a cibl&#233; les radicaux dans le but de parer les attaques terroristes potentielles. Par ailleurs, Mme Gillard a irrit&#233; certains musulmans australiens en d&#233;clarant en 2011 qu&#8217;elle soutenait les agences d&#8217;espionnage [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[972,386],"tags":[],"class_list":["post-15243","post","type-post","status-publish","format-standard","hentry","category-la-franc-maconnerie-en-roumanie-3480-fr","category-nouvelles-1602-fr"],"_links":{"self":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/15243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/comments?post=15243"}],"version-history":[{"count":0,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/15243\/revisions"}],"wp:attachment":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/media?parent=15243"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/categories?post=15243"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/tags?post=15243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}