{"id":15947,"date":"2020-03-25T23:03:03","date_gmt":"2020-03-25T23:03:03","guid":{"rendered":"http:\/\/dev.yogaesoteric.net\/la-tradition-du-yoga-fr\/de-la-sagesse-des-maitres-yogis-3712-fr\/la-cle-du-bonheur-selon-la-methode-japonaise-konmari\/"},"modified":"2020-03-25T23:03:03","modified_gmt":"2020-03-25T23:03:03","slug":"la-cle-du-bonheur-selon-la-methode-japonaise-konmari","status":"publish","type":"post","link":"https:\/\/yogaesoteric.net\/fr\/la-cle-du-bonheur-selon-la-methode-japonaise-konmari\/","title":{"rendered":"La cl\u00e9 du bonheur, selon la m\u00e9thode japonaise KonMari"},"content":{"rendered":"<p align=\"justify\">&#160;<\/p>\n<p align=\"justify\">Marie Kondo a conquis le monde, telle un tourbillon de rangement et de propret&#233;, laissant dans son sillage une organisation et un ordre &#224; faire p&#226;lir d&#8217;envie. Nous parlons ici de son ouvrage intitul&#233; La magie du rangement, paru en 2014. Entre son livre et ses &#233;mission, les lecteurs et les t&#233;l&#233;spectateurs sont d&#233;sormais pr&#234;ts &#224; entamer un d&#233;sencombrement rapide, spectaculaire et transformateur de leur domicile!<\/p>\n<p align=\"center\">\n    <img decoding=\"async\" alt=\"\" src=\"\/all_uploads\/uploads5\/martie%202020\/16\/22705_1.jpg\" \/>\n  <\/p>\n<p align=\"justify\">Mais la m&#233;thode KonMari va bien au-del&#224; de l&#8217;&#233;tiquetage de bacs &#224; rangement et du d&#233;poussi&#233;rage. Lisez cet article pour d&#233;couvrir la cl&#233; du bonheur, selon cette talentueuse essayiste!<\/p>\n<p align=\"justify\">\n    <strong>Visualisez votre objectif<\/strong><br \/>\n    <br \/>La m&#233;thode KonMari a beau &#234;tre universelle, car elle s&#8217;applique &#224; tout foyer, elle n&#233;cessite toutefois une motivation tr&#232;s personnelle. Avant de jeter quoi que ce soit, visualisez votre objectif et tentez de savoir pourquoi et comment vous compter y parvenir. <\/p>\n<p align=\"justify\">\n    <strong>Alors, heureux(se)?<br \/><\/strong>La premi&#232;re &#233;tape de la m&#233;thode KonMari consiste &#224; poser les mains sur toutes vos affaires en vous demandant si elles vous inspirent du bonheur. Ce proc&#233;d&#233; manuel n&#8217;a aucun rapport avec la v&#233;ritable utilit&#233; de l&#8217;objet. <\/p>\n<p align=\"justify\">\n    <strong>Avancer par cat&#233;gorie, pas par pi&#232;ce<\/strong><br \/>\n    <br \/>Il peut sembler logique d&#8217;aller de pi&#232;ce en pi&#232;ce, mais la premi&#232;re r&#232;gle de Kondo est de ranger par cat&#233;gorie. Elle conseille de commencer par les v&#234;tements, puis par les livres, les documents, les babioles et enfin par les vieilles photographies et les souvenirs.<\/p>\n<p align=\"justify\">\n    <strong>Sous-cat&#233;gories<\/strong><br \/>\n    <br \/>Chaque cat&#233;gorie se d&#233;cline &#233;galement en sous-cat&#233;gories, comme par exemple trier ses t-shirts un jour et ses pantalons le suivant.<\/p>\n<p align=\"justify\">\n    <strong>Respecter son domicile<\/strong><br \/>\n    <br \/>Prendre le temps de saluer et de remercier votre maison peut vous para&#238;tre &#233;trange, mais Kondo rend hommage &#224; chaque maison qu&#8217;elle range, la remerciant de ce qu&#8217;elle a apport&#233; au propri&#233;taire. <\/p>\n<p align=\"justify\">\n    <strong>Remercier ses possessions<br \/><\/strong>Kondo encourage &#233;galement les personnes &#224; remercier chaque objet pour son utilit&#233;, en particulier si vous le jetez. Cela facilitera grandement le processus. Vous appr&#233;cierez ainsi davantage ce que vous poss&#233;dez et apprendrez &#224; traiter chacun de vos objets avec respect. <\/p>\n<p align=\"justify\">\n    <strong>Soyez cr&#233;atifs<\/strong><br \/>\n    <br \/>Avez-vous d&#233;j&#224; pris en compte les sentiments de vos v&#234;tements? Kondo encourage les gens &#224; se demander si leurs v&#234;tements sont contents d&#8217;&#234;tre &#233;cras&#233;s, froiss&#233;s ou roul&#233;s en boule. <\/p>\n<p align=\"justify\">\n    <strong>&#201;viter &#224; tout prix la nostalgie<br \/><\/strong>Il est essentiel de rester dans le moment pr&#233;sent et de r&#233;fl&#233;chir &#224; ce qui vous rend actuellement heureux, par opposition &#224; ce qui a fait votre bonheur par le pass&#233;. Kondo explique que vous devriez trier vos souvenirs en dernier, pour que vous ayez le temps de cibler ce qui vous apporte v&#233;ritablement de la joie. <\/p>\n<p align=\"justify\">\n    <strong>Faire l&#8217;inventaire<br \/><\/strong>Il est essentiel de tout rassembler au m&#234;me endroit pour vraiment saisir la quantit&#233; d&#8217;objets que vous poss&#233;dez. Il s&#8217;agit d&#8217;un moyen efficace pour r&#233;aliser que vous n&#8217;avez pas besoin de tout, ce qui facilitera le rangement par le vide. <\/p>\n<p align=\"justify\">\n    <strong>Un bazard productif<br \/><\/strong>Selon la m&#233;thode KonMari, il faut g&#233;n&#233;ralement mettre le d&#233;sordre avant de tout replacer au bon endroit. En suivant cette logique, si votre domicile semble &#234;tre sans dessus-dessous, c&#8217;est que vous vous appr&#234;tez &#224; tout bien ranger! <\/p>\n<p align=\"justify\">\n    <strong>Ne pas jeter &#224; tout prix<br \/><\/strong>Plut&#244;t que de choisir de quoi vous d&#233;barrasser, Kondo conseille plut&#244;t de mettre l&#8217;accent sur ce que vous souhaitez garder. <\/p>\n<p align=\"justify\">\n    <strong>Vous &#234;tes autoris&#233; &#224; jeter tout ce qui ne vous sert pas<\/strong><br \/>\n    <br \/>Vous focaliser sur le bonheur vous donnera la permission de laisser tomber tout ce qui ne vous pla&#238;t plus, est us&#233;, vous met mal &#224; l&#8217;aise et que vous n&#8217;appr&#233;ciez plus vraiment. <\/p>\n<p align=\"justify\">\n    <strong>Karma<br \/><\/strong>Donnez vos vieux objets &#224; un magasin caritatif, car les choses qui ne vous ont pas procur&#233; de la joie pourraient faire le bonheur de quelqu&#8217;un d&#8217;autre. De plus, vous r&#233;duirez ainsi votre empreinte &#233;cologique! <\/p>\n<p align=\"justify\">\n    <strong>Plier et ranger &#224; la verticale<\/strong><br \/>\n    <br \/>C&#8217;est seulement apr&#232;s avoir tout tri&#233; que vous pourrez d&#233;cider o&#249; les &#233;l&#233;ments restants doivent &#234;tre conserv&#233;s. Kondo pense que beaucoup de nos v&#234;tements seraient mieux rang&#233;s (ou plus heureux, comme elle le dirait) une fois pli&#233;s dans une commode. <\/p>\n<p align=\"justify\">\n    <strong>La technique de pliage KonMari<\/strong><br \/>\n    <br \/>La technique de pliage vertical de Kondo rend tout facile &#224; rep&#233;rer et &#224; r&#233;cup&#233;rer sans d&#233;ranger les &#233;l&#233;ments alentours. Tout, des t-shirts aux pantalons, peut prendre la forme d&#8217;un long rectangle, puis &#234;tre repli&#233; par le bas en un joli petit paquet. Kondo sugg&#232;re &#233;galement d&#8217;utiliser des s&#233;parateurs de tiroir, comme une bo&#238;te &#224; chaussures. <\/p>\n<p align=\"justify\">\n    <strong>Aimer son armoire<\/strong><br \/>\n    <br \/>Plus de d&#233;sordre sur les &#233;tag&#232;res, ni de chemises froiss&#233;es: s&#8217;habiller le matin sera un vrai plaisir. <\/p>\n<p align=\"justify\">\n    <strong>Red&#233;couvrir son style<\/strong><br \/>\n    <br \/>Lorsque vous accumulez des v&#234;tements et portez continuellement les m&#234;mes tenues, vous pouvez facilement perdre de vue votre style. La m&#233;thode KonMari est un moyen de le red&#233;couvrir. <\/p>\n<p align=\"justify\">\n    <strong>Se d&#233;barrasser de la paperasse<\/strong><br \/>\n    <br \/>Tout le monde a un tiroir ou des classeurs remplis d&#8217;anciens papiers administratifs et de documents qui sont probablement d&#233;j&#224; tous disponibles num&#233;riquement. Ils constituent le summum de l&#8217;encombrement inutile. <\/p>\n<p align=\"justify\">\n    <strong>Mettre l&#8217;accent sur ses propres affaires<\/strong><br \/>\n    <br \/>Lorsque vous vivez en famille ou en colocation, il est parfois difficile de g&#233;rer le fouillis des autres. Kondo ne recommande pas d&#8217;interf&#233;rer dans leurs affaires. Donnez plut&#244;t le bon exemple en vous concentrant sur votre paperasse et en servant ainsi de mod&#232;le pour tous les autres. <\/p>\n<p align=\"justify\">\n    <strong>Ne plus empiler<\/strong><br \/>\n    <br \/>Tout, des documents aux v&#234;tements, en passant par le contenu de votre r&#233;frig&#233;rateur, peut et doit &#234;tre dispos&#233; verticalement pour que tout soit visible, accessible et facile &#224; saisir. Les &#233;tag&#232;res sont vos amies! <\/p>\n<p align=\"center\">\n    <img decoding=\"async\" alt=\"\" src=\"\/all_uploads\/uploads5\/martie 2020\/16\/22705_2.jpg\" \/>&#160;<br \/>Marie Kondo <\/p>\n<p align=\"justify\">\n    <strong>Garder sa bigaille<\/strong><br \/>\n    <br \/>Kondo ne comprend pas pourquoi les gens gardent leur monnaie dans des bocaux ou des tiroirs, dans tous les recoins de la maison. Cet argent devient inutile: quelle est la derni&#232;re fois o&#249; vous vous &#234;tes servi de votre bigaille? Kondo sugg&#232;re de remettre ces pi&#232;ces dans votre portefeuille lorsque vous les trouverez &#233;parpill&#233;es chez vous, afin de les d&#233;penser une bonne fois pour toutes. <\/p>\n<p align=\"justify\">\n    <strong>Faire son lit chaque matin<\/strong><br \/>\n    <br \/>Votre lit est l&#8217;&#233;l&#233;ment phare de votre chambre, cela signifie que la pi&#232;ce ne semblera pas rang&#233;e s&#8217;il n&#8217;est pas fait. <\/p>\n<p align=\"justify\">\n    <strong>D&#233;sencombrer ses lavabos<\/strong><br \/>\n    <br \/>Kondo sugg&#232;re de ne pas placer d&#8217;objets autour de l&#8217;&#233;vier ou du lavabo, car ils peuvent &#234;tre mouill&#233;s et rendre le rin&#231;age plus difficile. Autant que possible, &#233;vitez d&#8217;encombrer les endroits qui n&#233;cessitent un nettoyage plus fr&#233;quent. <\/p>\n<p align=\"justify\">\n    <strong>Les lieux de passage<\/strong><br \/>\n    <br \/>&#201;tiquetez les paniers dans les couloirs pour que tout le monde sache o&#249; ranger ses affaires et pour que les lieux de passage les plus fr&#233;quent&#233;s de votre maison restent d&#233;gag&#233;s. <\/p>\n<p align=\"justify\">\n    <strong>Tout a une place<\/strong><br \/>\n    <br \/>Assurez-vous qu&#8217;il existe un emplacement sp&#233;cifique pour chaque objet de votre maison, de sorte que vous sachiez o&#249; le ranger et que vous puissiez toujours le retrouver. <\/p>\n<p align=\"justify\">\n    <strong>Le d&#233;sordre affecte le mental<\/strong><br \/>\n    <br \/>Qu&#8217;il vous prive d&#8217;intimit&#233; dans la chambre &#224; coucher, vous emp&#234;che d&#8217;exprimer votre potentiel dans le salon ou mine votre moral en s&#8217;accumulant dans le grenier, le d&#233;sordre affectera votre mental, qu&#8217;importe la pi&#232;ce dans laquelle il se trouve. <\/p>\n<p align=\"justify\">\n    <strong>Tout faire d&#8217;une traite<\/strong><br \/>\n    <br \/>Le processus ne fonctionnera pas si vous faites les choses petit &#224; petit. Pas d&#8217;inqui&#233;tude: Kondo vous donne six mois pour tout accomplir! <\/p>\n<p align=\"justify\">\n    <strong>Ne pas se forcer &#224; jeter en cas de doute<\/strong><br \/>\n    <br \/>Contrairement &#224; certains minimalistes, Kondo ne conseille pas &#224; chacun de ne poss&#233;der qu&#8217;un tiroir pour ses v&#234;tements ou seulement sept t-shirts. La m&#233;thode KonMari peut s&#8217;adapter &#224; toutes sortes d&#8217;objets. <\/p>\n<p align=\"justify\">\n    <strong>Une histoire de bien-&#234;tre<\/strong><br \/>\n    <br \/>Kondo est convaincue que le bien-&#234;tre consiste &#224; comprendre ce qui suscite la joie dans votre vie et vous rend le plus heureux. Et une fois que vous avez acquis cette connaissance, vous pourrez l&#8217;appliquer &#224; la nourriture, &#224; vos relations, &#224; votre carri&#232;re et bien plus encore.<\/p>\n<p align=\"justify\">&#160;<\/p>\n<p align=\"justify\">\n    <strong>yogaesoteric<br \/>25 mars 2020<\/strong>\n  <\/p>\n<p align=\"justify\">&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#160; Marie Kondo a conquis le monde, telle un tourbillon de rangement et de propret&#233;, laissant dans son sillage une organisation et un ordre &#224; faire p&#226;lir d&#8217;envie. Nous parlons ici de son ouvrage intitul&#233; La magie du rangement, paru en 2014. Entre son livre et ses &#233;mission, les lecteurs et les t&#233;l&#233;spectateurs sont d&#233;sormais [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1283,14],"tags":[],"class_list":["post-15947","post","type-post","status-publish","format-standard","hentry","category-de-la-sagesse-des-maitres-yogis-3712-fr","category-spiritualite-universelle-fr"],"_links":{"self":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/15947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/comments?post=15947"}],"version-history":[{"count":0,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/15947\/revisions"}],"wp:attachment":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/media?parent=15947"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/categories?post=15947"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/tags?post=15947"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}