{"id":185049,"date":"2025-01-22T10:03:19","date_gmt":"2025-01-22T10:03:19","guid":{"rendered":"https:\/\/yogaesoteric.net\/?p=185049"},"modified":"2025-01-22T10:03:19","modified_gmt":"2025-01-22T10:03:19","slug":"lukraine-la-corruption-le-decryptage","status":"publish","type":"post","link":"https:\/\/yogaesoteric.net\/fr\/lukraine-la-corruption-le-decryptage\/","title":{"rendered":"L\u2019Ukraine : la corruption. Le d\u00e9cryptage"},"content":{"rendered":"<p style=\"text-align: right;\">par Oleg Nesterenko,<br \/>\nPr\u00e9sident du CCIE <em>(<\/em><a href=\"http:\/\/www.c-cie.eu\/\" target=\"_blank\" rel=\"noopener\"><em>www.c-cie.eu<\/em><\/a><em>)<\/em><\/p>\n<p>Que ce soit en France ou en Ukraine, la corruption est g\u00e9n\u00e9ralis\u00e9e, je doute que les gens soient sensibles aux frasques de Z\u00e9lensky, puisqu\u2019ils acceptent celles de leur gouvernement. Nous devrions exiger un audit des d\u00e9penses publiques. C\u2019est l\u2019argent du peuple, on devrait savoir o\u00f9 passe tout l\u2019argent pr\u00e9lev\u00e9s, alors que les services publics sont au plus bas et ne remplissent plus leurs r\u00f4les\u2026&#8230;.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-185074\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_1.jpg\" alt=\"\" width=\"560\" height=\"393\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_1.jpg 560w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_1-300x211.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>Le candidat au poste de directeur du FBI des Etats-Unis d\u2019Am\u00e9rique, Kash Patel, a promis d\u2019enqu\u00eater sur la fa\u00e7on dont Zelensky a d\u00e9pens\u00e9 l\u2019argent am\u00e9ricain. Patel a soulign\u00e9 que l\u2019enqu\u00eate viserait \u00e0 d\u00e9couvrir comment les autorit\u00e9s ukrainiennes g\u00e8rent l\u2019argent des contribuables am\u00e9ricains. Plus t\u00f4t, le Pentagone avait rapport\u00e9 que pendant la pr\u00e9sidence de Joe Biden, l\u2019Ukraine avait re\u00e7u une aide militaire des \u00c9tats-Unis s\u2019\u00e9levant \u00e0 plus de 62 milliards de dollars.<\/p>\n<p>Laissons les am\u00e9ricains faire la lumi\u00e8re sur les r\u00e9seaux de corruption et du d\u00e9tournement ukraino-am\u00e9ricain des fonds investis dans la guerre en Ukraine. Cela \u00e9tant, si \u00e0 l\u2019heure d\u2019aujourd\u2019hui chacun a d\u00e9j\u00e0 entendu parler de la pr\u00e9sence de la corruption en Ukraine, n\u00e9anmoins, les informations qui apparaissent sur le sujet persistent \u00e0 \u00eatre \u00e0 caract\u00e8re tout \u00e0 fait flou, g\u00e9n\u00e9ralis\u00e9, voir d\u00e9form\u00e9, surtout dans l\u2019espace m\u00e9diatique occidental qui se tient \u00e0 la ligne pr\u00e9d\u00e9termin\u00e9e de la propagande qui est la leur.<\/p>\n<p>En mettant de c\u00f4t\u00e9 le scandale qui s\u2019annonce sur les investissements de l\u2019administration am\u00e9ricaine sortante dans la guerre contre la F\u00e9d\u00e9ration de Russie, mon objectif par la pr\u00e9sente est d\u2019apporter la compr\u00e9hension des fondements et du fonctionnement du syst\u00e8me de corruption en Ukraine avec l\u2019apport de quelques exemples concrets d\u2019application.<\/p>\n<p>La r\u00e9alit\u00e9 dans laquelle la nation ukrainienne est profond\u00e9ment plong\u00e9e aujourd\u2019hui est tout \u00e0 fait \u00e9loign\u00e9e des narratifs propag\u00e9s par les mass-m\u00e9dias occidentaux, dont le mode op\u00e9ratoire \u00e9pous\u00e9 depuis un moment est celui de Joseph Goebbels, ministre de la Propagande du III\u00e8me Reich, qui stipule : \u00ab <em>Plus le mensonge est gros \u2013 mieux il passe !<\/em> \u00bb.<\/p>\n<p><strong>Partie I<\/strong><\/p>\n<p><strong>La corruption et l\u2019int\u00e9gration de l\u2019Ukraine dans l\u2019UE<\/strong><\/p>\n<p>Le 23 juin 2022, quatre mois apr\u00e8s que l\u2019Ukraine ait officiellement pr\u00e9sent\u00e9 sa demande d\u2019adh\u00e9sion \u00e0 l\u2019Union europ\u00e9enne, le 28 f\u00e9vrier 2022, l\u2019int\u00e9gralit\u00e9 des chefs d\u2019\u00c9tats et de gouvernements de l\u2019UE ont unanimement d\u00e9cid\u00e9 d\u2019accorder \u00e0 l\u2019Ukraine le statut de pays-candidat \u00e0 l\u2019adh\u00e9sion.<\/p>\n<p>Le 4 novembre 2023, la pr\u00e9sidente de la Commission europ\u00e9enne, Ursula Von der Leyen, \u00e9tant en visite \u00e0 Kiev pour \u00ab <em>discuter du chemin de l\u2019Ukraine vers l\u2019UE<\/em> \u00bb a d\u00e9clar\u00e9 \u00eatre \u00ab <em>impressionn\u00e9e<\/em> \u00bb par les r\u00e9formes que l\u2019Ukraine a mis en \u0153uvre en pleine guerre et \u00eatre \u00ab <em>s\u00fbre<\/em> \u00bb qu\u2019elle pourra tr\u00e8s prochainement entrer dans l\u2019UE.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-185071\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_2.jpg\" alt=\"\" width=\"560\" height=\"334\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_2.jpg 560w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_2-300x179.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>De son c\u00f4t\u00e9, le 5 octobre 2023, l\u2019ancien chef de la Commission europ\u00e9enne, Jean-Claude Juncker, a d\u00e9clar\u00e9 au quotidien allemand <em>Augsburger Allgemeine<\/em> : \u00ab <em>Quiconque a eu quelque chose \u00e0 voir avec l\u2019Ukraine sait que c\u2019est un pays corrompu \u00e0 tous les niveaux de la soci\u00e9t\u00e9<\/em> [\u2026] <em>Il ne faut pas faire de fausses promesses au peuple ukrainien, qui est dans la souffrance jusqu\u2019au cou<\/em> \u00bb.<\/p>\n<p>D\u00e9but d\u00e9cembre de la m\u00eame ann\u00e9e, le premier ministre hongrois Viktor Orban a officiellement qualifi\u00e9 de faux le rapport de la CE, supervis\u00e9 par sa pr\u00e9sidente, sur le respect par l\u2019Ukraine des quatre conditions pr\u00e9alables \u00e0 l\u2019adh\u00e9sion \u00e0 l\u2019UE, dont celui du niveau et des r\u00e9sultats de la lutte contre la corruption :<em>\u00a0<\/em>\u00ab<em> L\u2019Ukraine est connue comme l\u2019un des pays les plus corrompus au monde !<\/em>\u00a0<em>Cela<\/em> [l\u2019affirmation que l\u2019Ukraine a fait des progr\u00e8s vis-\u00e0-vis des conditions pos\u00e9es par l\u2019UE] <em>est une blague !<\/em> \u00bb, a-t-il d\u00e9clar\u00e9 en rajoutant que le rapport fabriqu\u00e9 par la Commission europ\u00e9enne selon lequel quatre des sept conditions pr\u00e9alables ont \u00e9t\u00e9 remplies par l\u2019Ukraine n\u2019est rien d\u2019autre qu\u2019un \u00ab <em>mensonge<\/em> \u00bb.<\/p>\n<p>En novembre 2024, l\u2019ancien ministre polonais Kulpa a d\u00e9clar\u00e9 que jusqu\u2019\u00e0 la moiti\u00e9 de l\u2019aide occidentale \u00e0 l\u2019Ukraine a \u00e9t\u00e9 vol\u00e9e \u00e0 l\u2019int\u00e9rieur du pays : \u00ab <em>de 30% \u00e0 50% selon les secteurs. L\u2019argent vol\u00e9 aurait pu \u00eatre utilis\u00e9 pour cr\u00e9er un budget annuel de soutien \u00e0 l\u2019Ukraine<\/em> \u00bb.<\/p>\n<p>Cela \u00e9tant, l\u2019un des principaux objectifs de l\u2019\u00e9tat ukrainien \u00e0 ce jour est bien l\u2019adh\u00e9sion dans l\u2019Union Europ\u00e9enne et, rappelons-le : l\u2019une des conditions <em>sine qua non<\/em> de l\u2019adh\u00e9sion d\u2019un pays au sein \u00e0 l\u2019UE est la lutte contre la corruption avec l\u2019affichage des preuves des succ\u00e8s ind\u00e9niables sur ce chemin.<\/p>\n<p>Durant les n\u00e9gociations de l\u2019entr\u00e9e dans l\u2019UE, chaque pays-candidat entre dans le processus de la pr\u00e9paration de l\u2019application de la l\u00e9gislation et des normes de l\u2019Union. En effet, le processus d\u2019adh\u00e9sion n\u00e9cessite de la part du candidat de mettre en \u0153uvre des r\u00e9formes fondamentales dans de nombreux domaines, dont l\u2019une des principales est la lutte contre la corruption.<\/p>\n<p>Toutefois, m\u00eame en prenant en compte les statistiques officielles erron\u00e9es sur la corruption par le monde qui classent l\u2019Ukraine qu\u2019en 104\u00e8me place sur les 180 <a href=\"https:\/\/cpi.ti-ukraine.org\/en\/\" target=\"_blank\" rel=\"noopener\"><u>list\u00e9s<\/u><\/a>, le pays continue \u00e0 se situer 28 positions plus bas que le pays \u00ab le plus corrompu \u00bb parmi les membres actuels de l\u2019UE, ce qui est tout, sauf une preuve du succ\u00e8s ind\u00e9niable dans la lutte contre la corruption.<\/p>\n<p>En ce qui concerne \u00ab le combat contre la corruption \u00bb qui est actuellement men\u00e9 en Ukraine, je ne peux que citer l\u2019un de ses illustres repr\u00e9sentants, Vitaly Shabunine, pr\u00e9sident du conseil d\u2019administration de l\u2019organisme public \u00ab <em>Centre anti-corruption<\/em> \u00bb et membre du Conseil public du \u00ab <em>Bureau anti-corruption d\u2019Ukraine<\/em> \u00bb, afin que vous puissiez appr\u00e9cier les normes morales et les priorit\u00e9s professionnelles de ce haut fonctionnaire de Zelensky qui s\u2019occupe dudit combat. L\u2019une de ses d\u00e9clarations publiques est sans \u00e9quivoque : \u00ab <em>Tous ceux qui ne sont pas d\u2019accord <\/em>[avec la politique du pouvoir en place \u00e0 Kiev, y compris au niveau des m\u00e9thodes de la lutte contre la corruption]<em> \u2013 il faut les envoyer au front et ainsi les faire \u00e9liminer !<\/em> \u00bb. Et ce ne sont gu\u00e8re des adversaires \u00e0 la politique de la pr\u00e9tendue lutte contre la corruption dont il a parl\u00e9, mais bien de ceux qui sont r\u00e9volt\u00e9s par l\u2019absence totale de cette derni\u00e8re.<\/p>\n<figure id=\"attachment_185068\" aria-describedby=\"caption-attachment-185068\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-185068\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_3.jpg\" alt=\"\" width=\"560\" height=\"364\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_3.jpg 560w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_3-300x195.jpg 300w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_3-210x136.jpg 210w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-185068\" class=\"wp-caption-text\">Vitaly Shabunine<\/figcaption><\/figure>\n<p><strong>La formule \u00ab ukrainienne \u00bb de la baisse de la corruption<\/strong><\/p>\n<p>Etant tout \u00e0 fait soucieux de d\u00e9montrer les bons r\u00e9sultats de la lutte contre la corruption, le pouvoir install\u00e9 \u00e0 Kiev a trouv\u00e9 la solution qui ne peut \u00eatre qualifi\u00e9e autrement que lumineuse : faire diminuer le nombre de poursuite en justice et de condamnation pour corruption. La formule est tr\u00e8s simple : pas de condamnation = pas de corruption.<\/p>\n<p>Si encore en 2021, ce sont 6860 personnes qui ont \u00e9t\u00e9 condamn\u00e9es pour faits de corruption \u2013 en 2023, m\u00eame ce chiffre d\u00e9j\u00e0 tout \u00e0 fait d\u00e9risoire vis-\u00e0-vis de la r\u00e9elle quantit\u00e9 de personnes directement impliqu\u00e9es dans la corruption en Ukraine est pass\u00e9 \u00e0 2420 personnes. Soit une baisse spectaculaire de 65% de condamnation.<\/p>\n<p>Par ailleurs, il est \u00e0 noter que m\u00eame en 2021, soit avant le d\u00e9but de la guerre, le chiffre mentionn\u00e9 de 6860 condamnations n\u2019a gu\u00e8re \u00e9t\u00e9 li\u00e9 \u00e0 des r\u00e9sultats d\u2019un r\u00e9el travail de lutte contre la corruption, mais, principalement, \u00e0 des constatations d\u2019irr\u00e9gularit\u00e9s au niveau des d\u00e9clarations annuelles obligatoires fiscales et de propri\u00e9t\u00e9 des fonctionnaires. Ainsi, les 75,9% des condamnations ont eu lieu sur la base d\u00e9clarative (<em>source : NAZK \u2013 Agence nationale de pr\u00e9vention de la corruption en Ukraine<\/em>).<\/p>\n<p>A la suite de l\u2019abolition de l\u2019obligation pour les fonctionnaires \u00e0 r\u00e9aliser les d\u00e9clarations annuelles des b\u00e9n\u00e9fices et de la propri\u00e9t\u00e9 individuelle qui a eu lieu en f\u00e9vrier 2022 \u2013 en 2023, ce chiffre est pass\u00e9 de 75,9% \u00e0 1,6% du total des condamnations. Ce qui n\u2019est gu\u00e8re \u00e9tonnant, vu que m\u00eame les peu nombreuses d\u00e9clarations soumises par les fonctionnaires dor\u00e9navant \u00e0 titre volontaire ne faisaient plus l\u2019objet d\u2019aucune inspection par l\u2019Agence nationale de pr\u00e9vention de la corruption en Ukraine, dont l\u2019action est devenue, tout simplement, inexistante.<\/p>\n<p><strong>La pr\u00e9sidence ukrainienne : l\u2019acc\u00e8s \u00e0 la succession de la corruption<\/strong><\/p>\n<p>Aujourd\u2019hui, le niveau de la corruption en Ukraine est nettement<strong>\u00a0<\/strong>sup\u00e9rieur \u00e0 celui de l\u2019\u00e9poque des six pr\u00e9sidents pr\u00e9c\u00e9dents et de leurs gouvernements respectifs qui \u00e9taient d\u00e9j\u00e0 connus, \u00e0 juste titre, pour la profondeur abyssale du niveau de leur corruption.<\/p>\n<p>En connaissant tr\u00e8s<strong>\u00a0<\/strong>bien l\u2019Ukraine \u00e0 titre personnel<strong>\u00a0<\/strong>depuis plus de 20 ans, je peux affirmer en parfaite connaissance de cause qu\u2019avec le coup d\u2019\u00e9tat de 2014, dont l\u2019une des raisons hautement<strong>\u00a0<\/strong>affich\u00e9es \u00e9tait le niveau in\u00e9gal\u00e9 de corruption du pr\u00e9sident renvers\u00e9 Viktor Ianoukovytch, l\u2019Ukraine a bascul\u00e9 vers le r\u00e9gime du pr\u00e9sident Petro Porochenko qui est devenu sensiblement plus corrompu que celui de son pr\u00e9d\u00e9cesseur.<\/p>\n<figure id=\"attachment_185065\" aria-describedby=\"caption-attachment-185065\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-185065\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_4.jpg\" alt=\"\" width=\"560\" height=\"325\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_4.jpg 560w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_4-300x174.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-185065\" class=\"wp-caption-text\">Petro Porochenko<\/figcaption><\/figure>\n<p>Il suffit de consulter les r\u00e9els avis de l\u2019\u00e9chantillon repr\u00e9sentatif des entreprises et de la population du pays pour conna\u00eetre cette r\u00e9alit\u00e9 sur la sensible aggravation de l\u2019\u00e9tat de corruption omnipr\u00e9sente et incontournable au sein de chaque organisme et cellule de l\u2019Etat sans aucune exception.<\/p>\n<p>Cinq ann\u00e9es du r\u00e8gne du pr\u00e9sident P. Porochenko se sont \u00e9coul\u00e9es et, une fois de plus, l\u2019arriv\u00e9e de V. Zelensky au pouvoir a \u00e9t\u00e9 en partie conditionn\u00e9e par un niveau record dans l\u2019histoire de l\u2019Ukraine de la corruption du pouvoir sortant. En votant pour Zelensky, les \u00be des \u00e9lecteurs ont surtout vot\u00e9 non pas pour ce dernier, mais contre le pr\u00e9sident Porochenko, en consid\u00e9rant que la corruption qui s\u2019est install\u00e9e au pays entre 2014 et 2019 a d\u00e9j\u00e0 atteint son apog\u00e9e et le changement de la gouvernance ne peut donc que la faire diminuer.<\/p>\n<p>La d\u00e9sillusion a \u00e9t\u00e9 rapide et brutale. Avec l\u2019arriv\u00e9e au pouvoir du nouveau r\u00e9gime, selon l\u2019avis objectif des repr\u00e9sentants des entreprises et de la soci\u00e9t\u00e9 ukrainienne, une fois de plus, la situation au niveau de la corruption s\u2019est aggrav\u00e9e davantage. Cela \u00e9tant, en mentionnant ces appr\u00e9ciations, il est \u00e0 souligner qu\u2019elles datent de la p\u00e9riode de 2019 \u00e0 2022, soit avant l\u2019entr\u00e9e de la Russie en guerre.<\/p>\n<p>D\u00e8s le d\u00e9clenchement de la phase active des hostilit\u00e9s en f\u00e9vrier 2022 et \u00e0 ce jour, selon mes nombreux interlocuteurs ukrainiens, le niveau de la corruption dans le pays s\u2019est approfondi, une fois de plus, en se transformant en une v\u00e9ritable fr\u00e9n\u00e9sie qui agit comme un rouleau compresseur non seulement vis-\u00e0-vis de l\u2019\u00e9conomie du pays en g\u00e9n\u00e9ral, mais \u00e9galement vis-\u00e0-vis de la quasi-int\u00e9gralit\u00e9 des citoyens \u00e0 tous les niveaux de leur vie.<\/p>\n<p>Par ailleurs, selon une enqu\u00eate men\u00e9e par la \u00ab <em>Plate-forme sociologique ukrainienne<\/em> \u00bb, du 7 au 14 octobre 2023, parmi les citoyens de l\u2019Ukraine \u00e2g\u00e9s de plus de 18 ans, pr\u00e8s de 90% des habitants de l\u2019Ukraine ont constat\u00e9 une augmentation du niveau de corruption dans le pays apr\u00e8s le d\u00e9but du conflit arm\u00e9.<\/p>\n<p>Les classements publi\u00e9s par des OGN, tels que Transparency International qui place l\u2019Ukraine qu\u2019en 104\u00e8me position sur les 180 des pays les plus corrompus pour l\u2019ann\u00e9e 2023 (contre la 116\u00e8me position en 2022) ne sont que des sophismes, des \u00e9tudes approximatives qui ne repr\u00e9sentent que le ressentiment g\u00e9n\u00e9ral d\u2019un \u00e9chantillon non repr\u00e9sentatif vis-\u00e0-vis de la corruption et ne refl\u00e8tent gu\u00e8re toute la profondeur du d\u00e9sastre de la r\u00e9alit\u00e9 que la soci\u00e9t\u00e9 ukrainienne est en train de vivre.<\/p>\n<p><strong>Partie II<\/strong><\/p>\n<p><strong>L\u2019ADN de la classe politique ukrainienne<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-185062\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_5.jpg\" alt=\"\" width=\"560\" height=\"389\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_5.jpg 560w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_5-300x208.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/>Ayant des connaissances pr\u00e9cises sur les processus constitutifs de la classe politique ukrainienne, l\u2019auteur des pr\u00e9sentes lignes peut affirmer que l\u2019int\u00e9gralit\u00e9 de la classe politique ukrainienne actuelle et des personnes qui ont pour objectif de la rejoindre ont la corruption ancr\u00e9e au niveau quasi-g\u00e9n\u00e9tique.<\/p>\n<p>Cette affirmation n\u2019est gu\u00e8re une exag\u00e9ration. La classe politique occidentale actuellement au pouvoir ne comprend ou, plus exactement, fait semblant de ne pas comprendre, que le sens m\u00eame de l\u2019activit\u00e9 politique en Ukraine est de g\u00e9n\u00e9rer d\u2019importants revenus financiers personnels. Revenus, qui ne peuvent \u00eatre atteints sans le recours \u00e0 la corruption \u00e0 grande \u00e9chelle. Et ceci est absolument \u00e0 tous les niveaux hi\u00e9rarchiques : en commen\u00e7ant par les petits \u00e9lus municipaux dans les villages et en terminant par la pr\u00e9sidence du pays, en passant par les nombreuses couches politico-administratives interm\u00e9diaires les s\u00e9parant.<\/p>\n<p>En parfaite connaissance de cause je peux affirmer que non pas la majorit\u00e9, mais bien l\u2019int\u00e9gralit\u00e9 des postes de d\u00e9cisionnaires dans les administrations d\u2019\u00e9tat et dans la fonction politique ukrainienne sont occup\u00e9s exclusivement soit par ceux qui les ont achet\u00e9s, soit par ceux qui y ont \u00e9t\u00e9 plac\u00e9s \/ \u00ab \u00e9lus \u00bb par de puissants protecteurs qui placent leurs pions, afin d\u2019atteindre les objectifs qui sont les leurs. Les chances d\u2019acc\u00e9der au pouvoir en Ukraine par un autre moyen sont, math\u00e9matiquement, proches de z\u00e9ro absolu.<\/p>\n<p>Des postes dans les administrations et des places dans la fonction politique au niveau local, d\u00e9partemental, r\u00e9gional et national s\u2019ach\u00e8tent, se monnayent et sont consid\u00e9r\u00e9s en tant que v\u00e9ritable investissement financier.<\/p>\n<p>Un investissement qui doit g\u00e9n\u00e9rer des b\u00e9n\u00e9fices concrets. Des b\u00e9n\u00e9fices qui n\u2019ont rien \u00e0 voir avec les salaires officiels totalement d\u00e9risoires attach\u00e9s aux postes en question. Notamment, selon l\u2019information re\u00e7ue d\u2019une relation personnelle qui \u00e9tait r\u00e9cemment cadre sup\u00e9rieur dans un parti politique ukrainien, le prix d\u2019un si\u00e8ge au Virhovna Rada (parlement ukrainien) se monnaie de 1 \u00e0 5 millions de dollars am\u00e9ricains. Et ce bar\u00e8me est identique pour tous les partis politiques confondus qui y si\u00e8gent.<\/p>\n<p>C\u2019est-\u00e0-dire, en Ukraine, une personne qui n\u2019a rien \u00e0 voir avec la politique, mais disposant de fonds financiers consid\u00e9rables provenant, en g\u00e9n\u00e9ral, de son activit\u00e9 d\u2019affaires et\/ou de la corruption sur les postes occup\u00e9s pr\u00e9c\u00e9demment, peut \u00e0 tout moment devenir d\u00e9put\u00e9 \u00ab \u00e9lu du people \u00bb d\u2019une mani\u00e8re garantie au sein de n\u2019importe quel parti politique tant au niveau r\u00e9gional qu\u2019au niveau national. Ce n\u2019est qu\u2019une question de prix.<\/p>\n<p>Aujourd\u2019hui, la corruption en Ukraine est au stade d\u2019une absolue fr\u00e9n\u00e9sie qui s\u2019explique directement par l\u2019absence de vision sur l\u2019avenir politique du pays, m\u00eame \u00e0 moyen terme, et donc sur la p\u00e9rennit\u00e9 de l\u2019investissement r\u00e9alis\u00e9 dans les si\u00e8ges de responsabilit\u00e9 politique et de la haute fonction : chacun faisant partie du \u00ab syst\u00e8me \u00bb essaie de g\u00e9n\u00e9rer un maximum de b\u00e9n\u00e9fices financiers avant la plong\u00e9e dans l\u2019inconnu que conna\u00eetra leur carri\u00e8re personnelle, due \u00e0 l\u2019effondrement politique, \u00e9conomique et soci\u00e9tale du pays qui approche \u00e0 grand pas et d\u2019une mani\u00e8re imminente.<\/p>\n<p><strong>La structure de la corruption ukrainienne<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-185059\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_6.jpg\" alt=\"\" width=\"560\" height=\"305\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_6.jpg 560w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_6-300x163.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/>Seuls les esprits qui n\u2019ont strictement aucune connaissance du pays et des rouages du fonctionnement de ses administrations et de ses partis politiques peuvent prendre le th\u00e8me de la pr\u00e9tendue lutte contre la corruption en Ukraine au s\u00e9rieux.<\/p>\n<p>L\u2019enqu\u00eate mentionn\u00e9e pr\u00e9c\u00e9demment, men\u00e9e en 2023 par la \u00ab <em>Plate-forme sociologique ukrainienne <\/em>\u00bb parmi les citoyens de l\u2019Ukraine, r\u00e9v\u00e8le \u00e9galement que la majorit\u00e9 \u00e9crasante des Ukrainiens estime que les autorit\u00e9s anticorruptions elles-m\u00eames \u00e9tant profond\u00e9ment corrompues contribuent \u00e0 l\u2019augmentation de la corruption dans le pays.<\/p>\n<p>Le syst\u00e8me de corruption en Ukraine est totalement in\u00e9branlable \u00e0 chacun de ses niveaux, car constitu\u00e9 de r\u00e9seaux hi\u00e9rarchiques interd\u00e9pendants, dont le partage de b\u00e9n\u00e9fices financiers et la s\u00e9curisation mutuelle vis-\u00e0-vis des menaces externes est son \u00e9l\u00e9ment constitutif.<\/p>\n<p>Chaque ministre, d\u00e9put\u00e9, juge, haut fonctionnaire des administrations, de la police et de la SBU (service de la s\u00e9curit\u00e9 int\u00e9rieure) fait partie du r\u00e9seau d\u2019une mani\u00e8re obligatoire. De m\u00eame que chacun des responsables se situant sur une \u00e9chelle plus basse des structures sous leurs juridictions respectives. Nulle place pour les \u00ab dissidents \u00bb qui puissent oser menacer le syst\u00e8me.<\/p>\n<p>La majorit\u00e9 \u00e9crasante des cas de succ\u00e8s de la \u00ab lutte \u00bb contre la corruption rendus public, afin d\u2019afficher la pr\u00e9tendue existence de cette derni\u00e8re, sont ceux, dont les figurants ont commis de graves fautes non pas vis-\u00e0-vis de la loi, mais vis-\u00e0-vis de la hi\u00e9rarchie du syst\u00e8me de corruption, notamment, en \u00e9tant malhonn\u00eate dans les partages financiers des fruits de la corruption adress\u00e9s \u00e0 leurs sup\u00e9rieurs hi\u00e9rarchiques. Ainsi les \u00ab brebis galeuses \u00bb sont s\u00e9v\u00e8rement punies et remplac\u00e9es.<\/p>\n<p>Rares sont les cas quand les faits de corruption sont d\u00e9couverts par des personnes ou organismes tierces au \u00ab syst\u00e8me \u00bb et rendus publics avant d\u2019\u00eatre \u00e9touff\u00e9s. Et m\u00eame dans ces cas de \u00ab force majeure \u00bb, les coupables ne sont que tr\u00e8s rarement punis par la loi : les affaires sont remises entre les mains de juges faisant partie du syst\u00e8me de corruption et aboutissent \u00e0 une d\u00e9cision judiciaire de non-lieu ou \u00e0 des condamnations tout \u00e0 fait d\u00e9risoires.<\/p>\n<p>Par le type et la s\u00e9v\u00e9rit\u00e9 de la condamnation d\u2019un fait de corruption il est possible de conna\u00eetre tr\u00e8s pr\u00e9cis\u00e9ment l\u2019appartenance de l\u2019inculp\u00e9 \u00e0 l\u2019une des deux cat\u00e9gories ci-dessus cit\u00e9es : une \u00ab brebis galeuse \u00bb qui a commis une faute vis-\u00e0-vis de ses sup\u00e9rieurs ou une victime de \u00ab force majeure \u00bb.<\/p>\n<p>Et c\u2019est bien vis-\u00e0-vis de ce syst\u00e8me de corruption ancr\u00e9 au niveau de l\u2019ADN de chacun de ces participants que l\u2019UE demande l\u2019\u00e9radication. En restant parfaitement r\u00e9aliste, on peut consid\u00e9rer que demander \u00e0 quelqu\u2019un de construire une fus\u00e9e spatiale \u00e0 partir d\u2019une bicyclette serait une requ\u00eate pas moins s\u00e9rieuse que celle formul\u00e9e par les europ\u00e9istes de Bruxelles aupr\u00e8s de ceux qui sont, donc, sens\u00e9s s\u2019auto-\u00e9liminer.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-185056\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_7.jpg\" alt=\"\" width=\"560\" height=\"389\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_7.jpg 560w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_7-300x208.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>Les m\u00e9dias de la propagande \u00ab atlantiste \u00bb \u2013 soit la quasi-int\u00e9gralit\u00e9 des m\u00e9dias occidentaux \u2013 en parlant de la corruption en Ukraine ne font que d\u00e9former et transgresser la r\u00e9alit\u00e9. Un simple exemple d\u2019une des nombreuses transgressions parues dans la presse fran\u00e7aise : \u00ab \u2026<em>Volodymyr Zelensky affiche en ce sens (vis-\u00e0-vis de la corruption) une tol\u00e9rance z\u00e9ro. Son nouveau ministre de la D\u00e9fense, nomm\u00e9 en septembre <\/em>[2023]<em> apr\u00e8s la chute dans le cadre d\u2019un scandale de corruption de son pr\u00e9d\u00e9cesseur, doit men<\/em><em>er de front une lutte contre la corruption et une lutte contre l\u2019agresseur russe. Car lorsque la guerre s\u2019ach\u00e8vera, il faudra que l\u2019Ukraine soit capable de g\u00e9rer les flux d\u2019argent pour la reconstruction, sans que ces aides soient d\u00e9tourn\u00e9es par ses \u00e9lites.<\/em> \u00bb<\/p>\n<p>Ne serait-ce que dans le cas de cet exemple parmi tant d\u2019autres, la transgression de la v\u00e9rit\u00e9 commandit\u00e9e par le pouvoir politique et r\u00e9alis\u00e9e via la presse publique occidentale est tout \u00e0 fait grossi\u00e8re et digne d\u2019un profond m\u00e9pris.<\/p>\n<p>Pour \u00eatre heurt\u00e9 \u00e0 la r\u00e9alit\u00e9, il suffit de se poser la question : si le fait de la corruption du ministre de D\u00e9fense d\u00e9chu (Oleksiy Rezniko) s\u2019est av\u00e9r\u00e9 confirm\u00e9 et largement connu par le grand public (le minist\u00e8re de la D\u00e9fense ukrainien a conclu des contrats pour un montant sup\u00e9rieur \u00e0 350 millions de dollars avec des fournisseurs de nourriture pour l\u2019arm\u00e9e, en d\u00e9boursant de deux \u00e0 trois fois le prix pratiqu\u00e9 sur le march\u00e9, dont l\u2019unique raison plausible d\u2019une telle activit\u00e9 est la perception d\u2019une r\u00e9trocommission), comment expliquer que cette personne n\u2019a jamais \u00e9t\u00e9 ni mise en examen par la justice ukrainienne, ni d\u00e9rang\u00e9e de quelque mani\u00e8re que cela soit ? Au lieu de poursuites judiciaires et d\u2019une peine de prison, ledit personnage a tranquillement pris sa retraite et m\u00e8ne ouvertement une vie de multimillionnaire, notamment \u00e0 Londres \u2013 et ceci apr\u00e8s avoir per\u00e7u un salaire d\u00e9risoire de ministre qui \u00e9tait d\u2019environ 2400 euros par mois, toutes primes incluses.<\/p>\n<p>Cette question est tout \u00e0 fait rh\u00e9torique \u2013 la r\u00e9ponse est expos\u00e9e dans ces pages.<\/p>\n<p>Ceux du r\u00e9gime instaur\u00e9 en Ukraine qui n\u2019ont pas l\u2019occasion de participer dans les r\u00e9seaux \u00ab classiques \u00bb de corruption, tels que les commandants des unit\u00e9s combattant au front, ont trouv\u00e9 la parade pour se remplir les poches \u00e0 l\u2019instar de leurs leaders politiques. D\u00e9but d\u00e9cembre 2024, la d\u00e9put\u00e9e du parlement ukrainien Skorokhod a \u00e9voqu\u00e9 la situation dans les rangs des forces arm\u00e9es ukrainiennes : \u00ab <em>Les commandants exigent de l\u2019argent des soldats. Si auparavant les sommes s\u2019\u00e9levaient <\/em><em>\u00e0 environ 5.000 hryvnias, maintenant elles sont de 25.000. Et si vous ne donnez pas l\u2019argent, ils vous enverront imm\u00e9diatement sur les positions les plus dangereuses de la premi\u00e8re ligne du front et il n\u2019est pas certain que vous reviendrez de l\u00e0-bas vivant<\/em> \u00bb.<\/p>\n<p><strong>Partie III<\/strong><\/p>\n<p><strong>La Th\u00e9mis de l\u2019\u00e9tat Orwellien<\/strong><\/p>\n<p>Le 5 septembre 2024, une nouvelle r\u00e9jouissante a \u00e9t\u00e9 re\u00e7ue par les partenaires Occidentaux de l\u2019Ukraine : madame Olga Stefanishina, vice-premier ministre ukrainien pour\u00a0l\u2019Int\u00e9gration Europ\u00e9enne et Euro-Atlantique a \u00e9t\u00e9 nomm\u00e9e \u00e0 l\u2019unanimit\u00e9 des voix par le parlement ukrainien au poste de ministre de la Justice.<\/p>\n<figure id=\"attachment_185053\" aria-describedby=\"caption-attachment-185053\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-185053\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_8.jpg\" alt=\"\" width=\"560\" height=\"386\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_8.jpg 560w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_8-300x207.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><figcaption id=\"caption-attachment-185053\" class=\"wp-caption-text\">Olga Stefanishina<\/figcaption><\/figure>\n<p>Hormis la responsabilit\u00e9 sur l\u2019int\u00e9gration europ\u00e9enne et Euro-Atlantique de l\u2019Ukraine, cette gente dame a \u00e9t\u00e9 choisie pour devenir le visage de la justice ukrainienne. Cette lourde responsabilit\u00e9 et, en m\u00eame temps, l\u2019honneur lui ont \u00e9t\u00e9 accord\u00e9s certainement pour son sens aigu de la justice et ses valeurs morales \u00e0 toute \u00e9preuve.<\/p>\n<p>Il y a juste un d\u00e9tail qui ne pose, bien \u00e9videmment, aucun souci ni aux tenants du pouvoir \u00e0 Kiev, ni aux amis euro-atlantique de l\u2019Ukraine qui connaissent fort bien madame Stefanishina. Un d\u00e9tail que je vais quand m\u00eame d\u00e9tailler en quelques lignes.<\/p>\n<p>Avant et au moment m\u00eame de sa nomination \u00e0 la t\u00eate du minist\u00e8re de la Justice ukrainien, Olga Stefanishina \u00e9tait, l\u2019air de rien, en \u00e9tat d\u2019inculpation pour corruption par la justice ukrainienne : elle est officiellement d\u00e9clar\u00e9e soup\u00e7onn\u00e9e de d\u00e9tournement de fonds publics et d\u2019abus de pouvoir en vertu de la partie 5 de l\u2019article 191 du code p\u00e9nal de l\u2019Ukraine (son nom figure sur liste des accus\u00e9s dans l\u2019affaire de corruption sous le num\u00e9ro 991\/7772\/23, dat\u00e9 du 26.09.2023).<\/p>\n<p>La premi\u00e8re audience pour l\u2019affaire p\u00e9nale de corruption de madame Olga Stefanishina a eu lieu aupr\u00e8s de la Haute Cour d\u2019anti-corruption d\u2019Ukraine, le 26 septembre 2023 et, depuis septembre 2024, l\u2019accus\u00e9e occupe le poste de ministre de la Justice ukrainienne. Le poste lui procurant, par la m\u00eame occasion, le pouvoir juridique direct sur ceux qui sont en train de la juger.<\/p>\n<p>Il serait faire preuve d\u2019une grande l\u00e9g\u00e8ret\u00e9 d\u2019esprit pour imaginer que dans un pays Orwellien o\u00f9 un accus\u00e9 dans une affaire p\u00e9nale devient ministre de la Justice, ce dernier ne serait pas d\u00e9clar\u00e9 non coupable pour les faits incrimin\u00e9s.<\/p>\n<p><strong>Consortium \u00ab Bulding UA \u00bb<\/strong><\/p>\n<p>Parmi une grande quantit\u00e9 de cas de grande corruption que l\u2019Ukraine conna\u00eet au quotidien et dont j\u2019ai l\u2019embarras du choix pour les exposer, je vous en ai choisi un qui touche le domaine des travaux publics et, en m\u00eame temps, celui de la g\u00e9n\u00e9ration des b\u00e9n\u00e9fices de corruption gr\u00e2ce \u00e0 de gigantesques pertes humaines sur les champs de batailles, dont une grande partie est due aux civils envoy\u00e9s de force par le r\u00e9gime de Zelensky \u00e0 ce qu\u2019on peut difficilement qualifier autrement qu\u2019\u00e0 l\u2019abattoir.<\/p>\n<p>Il s\u2019agit du projet de construction pr\u00e8s de Kiev du plus grand cimeti\u00e8re militaire de l\u2019Ukraine.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-185050\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_9.jpg\" alt=\"\" width=\"560\" height=\"280\" srcset=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_9.jpg 560w, https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_9-300x150.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<p>L\u2019appel d\u2019offre pour la construction pr\u00e8s de Kiev de ce cimeti\u00e8re militaire a \u00e9t\u00e9 remport\u00e9 par l\u2019entreprise ki\u00e9vienne \u00ab <em>Consortium <\/em><em>&#8220;<\/em><em>Bulding UA<\/em><em>&#8220;<\/em><em>\u00a0<\/em>\u00bb, dont l\u2019offre s\u2019\u00e9levait \u00e0 1,75 milliard de hryvnias (dans les 40 millions d\u2019euros).<\/p>\n<p>Le fait que c\u2019est cette soci\u00e9t\u00e9 et pas une autre qui a \u00e9t\u00e9 retenue pour la r\u00e9alisation du projet des travaux publics d\u2019une importance nationale d\u00e9montre certainement qu\u2019elle s\u2019est av\u00e9r\u00e9e \u00eatre la meilleure au niveau du rapport qualit\u00e9\/prix propos\u00e9 et parmi les plus comp\u00e9tentes sur le territoire de l\u2019Ukraine dans le domaine des travaux publics.<\/p>\n<p>Jusqu\u2019au l\u00e0 tout va bien. Mais ce n\u2019est pas tout. La particularit\u00e9 de ce Consortium constitu\u00e9 de trois entreprises (originaires des villes d\u2019Odessa, du Dniepr et de la r\u00e9gion de Kiev) et qui devait avoir l\u2019air d\u2019une joint-venture tout \u00e0 fait ordinaire est dans le fait qu\u2019il a \u00e9t\u00e9 cr\u00e9\u00e9 le 04.07.2024 \u2013 1 jour apr\u00e8s l\u2019annonce de l\u2019appel d\u2019offres en question. Et le montant du capital social de ce \u00ab nouveau-n\u00e9 \u00bb qui a remport\u00e9 l\u2019appel d\u2019offre avoisinant les 40 millions d\u2019euros est remarquable : 1 million de grivnas, soit dans les 22.500 euros.<\/p>\n<p>En dehors m\u00eame des \u00e9l\u00e9ments expos\u00e9s qui feraient d\u00e9j\u00e0 l\u2019objet d\u2019un examen judiciaire dans un pays o\u00f9 la lutte contre la corruption existerait comme telle, l\u2019analyse des \u00e9l\u00e9ments du dossier de r\u00e9ponse du gagnant de l\u2019appel d\u2019offre par un syst\u00e8me ukrainien ind\u00e9pendant \u00ab <em>Youcontrol<\/em> \u00bb a conclu que non seulement le dossier du soumissionnaire \u00ab <em>Consortium <\/em><em>&#8220;<\/em><em>Bulding UA<\/em><em>&#8220;<\/em><em>\u00a0<\/em>\u00bb ne disposait pas d\u2019\u00e9l\u00e9ments n\u00e9cessaires pour la r\u00e9alisation du projet, mais ne pouvait m\u00eame pas \u00eatre autoris\u00e9 \u00e0 prendre part \u00e0 l\u2019appel d\u2019offre en question.<\/p>\n<p>Strictement aucune action de la part des autorit\u00e9s, ni aucun mis en examen n\u2019a eu et n\u2019aura, bien \u00e9videmment, jamais lieu dans cette affaire, malgr\u00e9 qu\u2019elle ait fait l\u2019objet d\u2019une divulgation et d\u2019un scandale au niveau national. Ce qui signifie qu\u2019une seule chose : dans ce projet il existe des r\u00e9trocommissions, dont les b\u00e9n\u00e9ficiaires sont les personnes se situant au sommet de la pyramide de la corruption ukrainienne.<\/p>\n<p>Cela \u00e9tant, ce n\u2019est qu\u2019un exemple parmi tant d\u2019autres de la corruption flagrante qui est un \u00e9l\u00e9ment normal et m\u00eame constitutif de la vie \u00e9conomique du candidat \u00e0 l\u2019adh\u00e9sion dans l\u2019Union Europ\u00e9enne qui est l\u2019Ukraine.<\/p>\n<p><strong>Le tour de passe-passe l\u00e9gislatif dans la protection de la corruption<\/strong><\/p>\n<p>Le code p\u00e9nal de l\u2019Ukraine, de m\u00eame que le code p\u00e9nal de chaque pays, contiennent des dispositifs et proc\u00e9dures p\u00e9nales s\u2019appliquant \u00e0 des infractions p\u00e9nales de corruption.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-185080 size-full\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_10-e1737540089659.webp\" alt=\"\" width=\"560\" height=\"302\" \/><\/p>\n<p>Dans le cadre de la politique de l\u2019int\u00e9gration europ\u00e9enne et selon les exigences de l\u2019UE (contre la d\u00e9livrance \u00e0 l\u2019Ukraine de 4 milliards d\u2019euros d\u2019aide suppl\u00e9mentaire), le 29 octobre 2024, la Verkhovna Rada (parlement) a adopt\u00e9 la loi (No 4033-IX) portant modification au code p\u00e9nal et au code des proc\u00e9dures p\u00e9nales s\u2019appliquant \u00e0 la coop\u00e9ration avec la justice des auteurs des infractions p\u00e9nales de corruption.<\/p>\n<p>Notamment, son article 77 concernant les dispositifs s\u2019appliquant aux personnes soup\u00e7onn\u00e9es de corruption qui coop\u00e8rent avec l\u2019enqu\u00eate en d\u00e9non\u00e7ant les complices et en apportant la r\u00e9paration des pr\u00e9judices, a \u00e9t\u00e9 compl\u00e9t\u00e9 par une seconde partie pr\u00e9voyant la possibilit\u00e9 de confiscation des biens de la personne incrimin\u00e9e : \u00ab<em> 2. En cas d\u2019exemption de l\u2019ex\u00e9cution d\u2019une peine avec probation sur la base d\u2019un accord de plaidoyer dans le c<\/em><em>adre d\u2019une proc\u00e9dure p\u00e9nale concernant une infraction p\u00e9nale de corruption ou une infraction p\u00e9nale li\u00e9e \u00e0 la corruption, sous r\u00e9serve de l\u2019accord entre les parties, une peine suppl\u00e9mentaire sous forme de confiscation de biens peut \u00e9galement \u00eatre inflig\u00e9e <\/em>\u00bb<em>.<\/em><\/p>\n<p>\u00c0 la suite de cet apport de \u00ab l\u2019harmonisation \u00bb au code p\u00e9nal ukrainien vis-\u00e0-vis de ceux de l\u2019espace europ\u00e9en, Kiev a re\u00e7u les 4 milliards d\u2019euros promis par Bruxelles.<\/p>\n<p>Seulement, 22 jours apr\u00e8s l\u2019adaptation de la loi No 4033-IX, le 20 novembre 2024, la Verkhovna Rada adopte une nouvelle loi (No 4074-IX) portant une nouvelle modification au code p\u00e9nal et au code des proc\u00e9dures p\u00e9nales s\u2019appliquant \u00e0 des infractions p\u00e9nales de corruption. Dans cette nouvelle r\u00e9daction de la loi, la partie 2 de l\u2019article 77 du code p\u00e9nal est \u00e9galement modifi\u00e9 ? Non, tout est bien plus simple : elle dispara\u00eet, tout simplement.<\/p>\n<p>Ainsi, le code p\u00e9nal de l\u2019Ukraine revient dans son \u00e9tat \u00ab originel \u00bb et ne pr\u00e9voit plus aucune possibilit\u00e9 de confiscation de bien des fonctionnaires condamn\u00e9s dans les affaires de corruption, s\u2019ils coop\u00e8rent avec l\u2019instruction : ils peuvent dormir tranquille et ne plus s\u2019inqui\u00e9ter pour le destin de leurs biens mal acquis qui ont \u00e9t\u00e9 mis en danger durant les 22 jours de l\u2019existence de la loi adopt\u00e9e fin octobre 2024.<\/p>\n<p>Manque de chance, le tour de passe-passe l\u00e9gislatif dans la protection de la corruption par les \u00ab \u00e9lus du peuple \u00bb si\u00e9geant au parlement ukrainien a \u00e9t\u00e9 d\u00e9couvert. Apr\u00e8s que leur l\u2019initiative lumineuse soit devenue connue du grand public, un v\u00e9ritable scandale \u00e0 l\u2019\u00e9chelle national a \u00e9clat\u00e9 (il est \u00e0 noter que, c\u00f4t\u00e9 Union Europ\u00e9enne escroqu\u00e9e par Kiev \u00e0 hauteur de 4 milliards d\u2019euros de plus, Bruxelles n\u2019a pas prononc\u00e9 un mot sur le sujet, de m\u00eame que les m\u00e9dias mainstream occidentaux de propagande).<\/p>\n<p>Bien que le peuple ukrainien soit aujourd\u2019hui opprim\u00e9, pers\u00e9cut\u00e9 et abaiss\u00e9 par le r\u00e9gime de Zelensky au niveau d\u2019un simple troupeau de b\u00e9tail tremblant de peur sous la menace permanente de r\u00e9pression, dont le niveau a grandement d\u00e9pass\u00e9 celui des ann\u00e9es 1930 sous le r\u00e9gime de Staline, \u2013 la tentative des \u00ab repr\u00e9sentants du peuple \u00bb \u00e0 faire d\u00e9tourner la l\u00e9gislation pour la pr\u00e9servation des biens pill\u00e9s, vol\u00e9s et escroqu\u00e9s par les fonctionnaires-repr\u00e9sentants du pouvoir a d\u00e9pass\u00e9 l\u2019entendement et a donc fait soulever des voix m\u00eame au sein des masses opprim\u00e9es et habitu\u00e9es \u00e0 se taire, afin de ne pas attirer les foudres de la r\u00e9pression.<img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-185077 size-full\" src=\"https:\/\/yogaesoteric.net\/wp-content\/uploads\/2025\/01\/185049_11-e1737540136872.webp\" alt=\"\" width=\"560\" height=\"315\" \/><\/p>\n<p>Alors, le pouvoir install\u00e9 \u00e0 Kiev a d\u00fb reculer et abandonner son initiative qui faisait r\u00eaver la l\u00e9gion de fonctionnaires ukrainiens corrompus. Le d\u00e9put\u00e9 Serguei Ionouchas, le repr\u00e9sentant du parti de Zelensky \u00ab Serviteurs du peuple \u00bb a comment\u00e9 la tentative \u00e9chou\u00e9e en tant qu\u2019une simple malheureuse erreur technico-juridique commise par ses auteurs et a promis de la corriger.<\/p>\n<p><strong>Le patronat \u00ab atlantiste \u00bb<\/strong><\/p>\n<p>C\u2019est bien ce r\u00e9gime totalitaire ne disposant d\u2019aucune vision, m\u00eame th\u00e9orique, sur ce qui est le fonctionnement d\u2019un \u00e9tat avec la structure portante autre que celle de la corruption, est celui qui est directement instaur\u00e9, orchestr\u00e9 et soutenu sous perfusion tout au long des ann\u00e9es par le pouvoir Occidental qui le d\u00e9tient qu\u2019en tant qu\u2019outil p\u00e9rissable de la lutte contre le renouveau de la puissance de la F\u00e9d\u00e9ration de Russie face aux int\u00e9r\u00eats de l\u2019Occident collectif et de ses \u00e9lites politico-financiers.<\/p>\n<p>Les tenants du pouvoir des capitales occidentales font passer leur \u00ab cr\u00e9ature \u00bb pour un cas exemplaire de la lutte pour des \u00ab valeurs d\u00e9mocratiques \u00bb via l\u2019appareil de propagande des m\u00e9dias mainstream aupr\u00e8s des masses \u00e9lectorales Occidentales profond\u00e9ment m\u00e9pris\u00e9es et transform\u00e9es en un troupeau de moutons, dont l\u2019unique r\u00f4le est de cautionner les budgets des engagements de leurs bergers nationaux et supranationaux.<\/p>\n<p>Les pr\u00e9sidents et les gouvernements successifs des Etats-Unis d\u2019Am\u00e9rique, du Royaume-Uni, de l\u2019Allemagne, de la France et de quelques autres plus modestes satellites-outils du ma\u00eetre outre-Atlantique agissent en association de malfaiteurs, dont l\u2019objectif constitutif est la domination d\u2019autres nations, afin de p\u00e9renniser la g\u00e9n\u00e9ration des b\u00e9n\u00e9fices financiers avec le minima de contrepartie. Ils sont directement coupables de l\u2019encouragement et de la prolif\u00e9ration par le monde des crimes contre l\u2019humanit\u00e9 et des assassinats \u00e0 l\u2019\u00e9chelle des nations.<\/p>\n<p>La mise en danger par des acteurs du monde non-occidental du rapport \u00ab dominant-domin\u00e9 \u00bb instaur\u00e9 depuis un demi-mill\u00e9naire et qui m\u00e8ne vers une grave diminution des b\u00e9n\u00e9fices financiers, fait entrer le bloc \u00ab atlantiste \u00bb dans un \u00e9tat d\u2019agressivit\u00e9 toute particuli\u00e8re qui ne pr\u00e9sage rien de bon pour le monde dans les d\u00e9cennies \u00e0 venir.<\/p>\n<p>En ce qui concerne le positionnement de leur \u00ab cr\u00e9ature \u00bb, qui est le pouvoir actuellement install\u00e9 \u00e0 Kiev, vis-\u00e0-vis de la guerre en cours : elle doit continuer, quel que soit le prix \u00e0 payer par l\u2019Ukraine et son peuple. Car le jour o\u00f9 la guerre s\u2019arr\u00eatera et si le r\u00e9gime de Zelensky est renvers\u00e9, les faits expos\u00e9s sur ces pages para\u00eetront tout \u00e0 fait modestes vis-\u00e0-vis de l\u2019ampleur des faits de corruption qui seront mis en lumi\u00e8re.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>yogaesoteric<br \/>\n22 janvier 2025<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>par Oleg Nesterenko, Pr\u00e9sident du CCIE (www.c-cie.eu) Que ce soit en France ou en Ukraine, la corruption est g\u00e9n\u00e9ralis\u00e9e, je doute que les gens soient sensibles aux frasques de Z\u00e9lensky, puisqu\u2019ils acceptent celles de leur gouvernement. Nous devrions exiger un audit des d\u00e9penses publiques. C\u2019est l\u2019argent du peuple, on devrait savoir o\u00f9 passe tout l\u2019argent [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[981],"tags":[1521],"class_list":["post-185049","post","type-post","status-publish","format-standard","hentry","category-sur-la-perverse-manipulation-maconnique-3480-fr","tag-semaine"],"_links":{"self":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/185049","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/comments?post=185049"}],"version-history":[{"count":1,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/185049\/revisions"}],"predecessor-version":[{"id":185083,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/185049\/revisions\/185083"}],"wp:attachment":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/media?parent=185049"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/categories?post=185049"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/tags?post=185049"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}