{"id":23259,"date":"2020-03-09T12:56:33","date_gmt":"2020-03-09T12:56:33","guid":{"rendered":"http:\/\/dev.yogaesoteric.net\/sante-fr\/articles-4260-fr\/du-the-vert-pour-les-muscles-des-sportifs\/"},"modified":"2020-03-09T12:56:33","modified_gmt":"2020-03-09T12:56:33","slug":"du-the-vert-pour-les-muscles-des-sportifs","status":"publish","type":"post","link":"https:\/\/yogaesoteric.net\/fr\/du-the-vert-pour-les-muscles-des-sportifs\/","title":{"rendered":"Du th\u00e9 vert pour les muscles des sportifs"},"content":{"rendered":"<p><\/p>\n<p align=\"justify\">\n    <br \/>\nUn extrait de th&#233; vert r&#233;duit les dommages aux fibres musculaires des sportifs.\n<\/p>\n<p align=\"center\">\n    <img decoding=\"async\" alt=\"\" src=\"\/all_uploads\/uploads5\/martie 2020\/6\/22626_1.jpg\" \/>\n  <\/p>\n<p>Dans une &#233;tude de 4 semaines, des chercheurs ont &#233;tudi&#233; l&#8217;effet d&#8217;un suppl&#233;ment quotidien de th&#233; vert, source de 640mg de polyph&#233;nols, sur 35 jeunes hommes s&#233;dentaires soumis &#224; un entra&#238;nement sportif. 17 d&#8217;entre eux ont re&#231;u le compl&#233;ment alimentaire de th&#233; vert et les 18 autres ont re&#231;u un placebo.<\/p>\n<p>Apr&#232;s 4 semaines de suppl&#233;mentation les chercheurs constatent que le th&#233; vert a augment&#233; la teneur en polyph&#233;nols du sang et la capacit&#233; antioxydante totale. Au terme de l&#8217;entra&#238;nement de musculation d&#8217;intensit&#233; mod&#233;r&#233;e les chercheurs constatent une diminution significative des radicaux libres produits par l&#8217;exercice. De plus, l&#8217;activit&#233; de la cr&#233;atine kinase, un marqueur des dommages musculaires, retombe plus rapidement apr&#232;s l&#8217;exercice dans le groupe th&#233; vert que dans le groupe placebo.<\/p>\n<p>Les chercheurs concluent que le th&#233; vert peut prot&#233;ger des dommages provoqu&#233;s par les radicaux libres induits par l&#8217;exercice chez des sujets s&#233;dentaires aussi bien dans le cadre des efforts d&#8217;endurance que pour les sports de force. Th&#233;oriquement une r&#233;duction des dommages musculaires signe une r&#233;cup&#233;ration plus rapide et pourrait se traduire &#224; long terme par des gains de masse musculaire et de performance, des points que la recherche doit encore d&#233;montrer.<\/p>\n<p><strong>yogaesoteric<br \/>\n9 mars 2020<\/strong><\/p>\n<p><\/p>\n<p>&#160;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un extrait de th&#233; vert r&#233;duit les dommages aux fibres musculaires des sportifs. Dans une &#233;tude de 4 semaines, des chercheurs ont &#233;tudi&#233; l&#8217;effet d&#8217;un suppl&#233;ment quotidien de th&#233; vert, source de 640mg de polyph&#233;nols, sur 35 jeunes hommes s&#233;dentaires soumis &#224; un entra&#238;nement sportif. 17 d&#8217;entre eux ont re&#231;u le compl&#233;ment alimentaire de th&#233; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[1045],"tags":[],"class_list":["post-23259","post","type-post","status-publish","format-standard","hentry","category-articles-4260-fr"],"_links":{"self":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/23259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/comments?post=23259"}],"version-history":[{"count":0,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/23259\/revisions"}],"wp:attachment":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/media?parent=23259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/categories?post=23259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/tags?post=23259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}