{"id":25011,"date":"2018-03-26T18:52:17","date_gmt":"2018-03-26T18:52:17","guid":{"rendered":"http:\/\/dev.yogaesoteric.net\/yoga-ro\/tehnici-yoga-simple-1587-ro\/la-relaxation-dynamique-de-caycedo-3\/"},"modified":"2018-03-26T18:52:17","modified_gmt":"2018-03-26T18:52:17","slug":"la-relaxation-dynamique-de-caycedo-3","status":"publish","type":"post","link":"https:\/\/yogaesoteric.net\/fr\/la-relaxation-dynamique-de-caycedo-3\/","title":{"rendered":"La relaxation dynamique de Caycedo (3)"},"content":{"rendered":"<p align=\"justify\">\n    \n  <\/p>\n<p align=\"justify\">Lisez la&#160;<a style=\"color: \" href=\"\/moved_content.php?lang=FR&amp;item=15203\" target=\"_blank\" rel=\"noopener\">deuxi&#232;me partie<\/a> de cet article&#160;<\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"justify\">\n    <strong>Exercice respiratoire n&#176; 4 <\/strong>\n  <\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"center\">\n    <img loading=\"lazy\" decoding=\"async\" style=\"border-top-color: ; border-left-color: ; border-bottom-color: ; border-right-color: \" border=\"0\" hspace=\"5\" alt=\"\" vspace=\"5\" src=\"\/all_uploads\/uploads-dec17\/martie\/26.03\/15313\/15313_1.jpg\" width=\"350\" height=\"521\" \/>&#160;<\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"justify\">Cet exercice se d&#233;roule en trois temps : <\/p>\n<p align=\"justify\">l) On tend le bras droit en avant, on inspire par la bouche en fermant le poing et, tout en retenant l&#8217;air, on effectue quelques rotations avec le bras, puis on expulse l&#8217;air fortement par le nez, le bras s&#8217;arr&#234;tant simultan&#233;ment &#224; la position de d&#233;part. En gardant le bras tendu, on essaie une relaxation physique et mentale dans la m&#234;me tension ou posture (cet exercice utilise le m&#234;me principe que certains proc&#233;d&#233;s zen). <\/p>\n<p align=\"justify\">2) On recommence le m&#234;me exercice avec le bras gauche. <\/p>\n<p align=\"justify\">3) On effectue le m&#234;me exercice avec les deux bras. Ce dernier temps se r&#233;p&#232;te deux fois, de mani&#232;re que l&#8217;activation psychophysique soit intense, le premier pour la &#171; relaxation zen &#187; et le second comme pr&#233;alable &#224; la relaxation ult&#233;rieure en d&#233;cubitus dorsal. <\/p>\n<p align=\"justify\">\n    <strong>Relaxation en d&#233;cubitus dorsal<\/strong>\n  <\/p>\n<p align=\"justify\">Le sujet se couche &#224; m&#234;me le sol, en position libre et s&#8217;abandonne &#224; la r&#233;cup&#233;ration ; la dur&#233;e de cette relaxation en d&#233;cubitus dorsal doit &#234;tre suffisamment longue pour permettre une r&#233;cup&#233;ration totale. Le terpnos-logos du directeur de groupe visera essentiellement &#224; approfondir l&#8217;&#233;tat de conscience et &#224; produire une obnubilation plus grande. Pendant les deux premi&#232;res semaines d&#8217;entra&#238;nement, on ne donnera aucun exercice de concentration mentale, le patient restant compl&#232;tement libre, apprenant ainsi &#171; &#224; conna&#238;tre et &#224; manier ses niveaux de conscience &#187;. En terminant cet exercice de relaxation, on fait r&#233;cup&#233;rer l&#8217;&#233;tat psychophysique ordinaire, aussi bien psychiquement que physiquement. Pour cela, on fera &#233;tirer les doigts, les bras, les jambes, etc. Les sujets ne doivent pas se lever avant d&#8217;avoir r&#233;cup&#233;r&#233; enti&#232;rement. Le directeur de groupe dirigera cette r&#233;cup&#233;ration compl&#232;te au moyen du terpnos-logos habituel. <\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"justify\">\n    <strong>Deuxi&#232;me partie (troisi&#232;me et quatri&#232;me semaines)<\/strong>\n  <\/p>\n<p align=\"justify\">Dans cette deuxi&#232;me partie, on proc&#232;de au NETI-KRIYA deux fois par semaine. A partir de la troisi&#232;me semaine, pendant la relaxation en d&#233;cubitus dorsal, apr&#232;s un temps de r&#233;cup&#233;ration physique, le sophrologue directeur du groupe commencera par le terpnos-logos l&#8217;exercice mental de concentration et de m&#233;ditation en r&#233;servant l&#8217;exercice de contemplation pour la derni&#232;re relaxation en d&#233;cubitus. Le sophrologue directeur de groupe sugg&#233;rera que chacun, partant de l&#8217;&#233;tat d&#8217;obnubilation profond de la conscience, commence &#224; fixer son esprit sur un objet d&#233;termin&#233;. Peu importe la nature de cet objet ; il est cependant pr&#233;f&#233;rable de prendre un objet naturel : l&#8217;eau, les nuages, les arbres ; la concentration ou fixation de l&#8217;esprit sur son objet durera quelques minutes et, l&#8217;exercice termin&#233;, on proc&#233;dera &#224; la sortie de la relaxation comme au cours des deux semaines pr&#233;c&#233;dentes. Dans cette deuxi&#232;me partie, le sujet debout poursuivra ses exercices en essayant de maintenir, non seulement l&#8217;obnubilation de sa conscience mais, en outre, en essayant de m&#233;diter sur l&#8217;objet qui lui a servi &#224; se concentrer. La m&#233;ditation, dans cette forme particuli&#232;re adapt&#233;e par Caycedo, est d&#233;crite dans les YOGA-SUTRAS comme un effort volontaire pour faire durer en quelque sorte l&#8217;image mentale qui s&#8217;est form&#233;e au cours de la concentration sur un objet. <\/p>\n<p align=\"justify\">\n    <strong>Exercice des poignets<\/strong>\n  <\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"center\">\n    <img decoding=\"async\" style=\"border-top-color: ; border-left-color: ; border-bottom-color: ; border-right-color: \" border=\"0\" hspace=\"5\" alt=\"\" vspace=\"5\" src=\"\/all_uploads\/uploads-dec17\/martie\/26.03\/15313\/15313_2.jpg\" \/>&#160;<\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"justify\">1) Debout, les bras tendus en avant, les doigts &#233;cart&#233;s comme si l&#8217;on voulait faire ses griffes, on am&#232;ne les mains au niveau des &#233;paules en inspirant par le nez, avec flexion des poignets, avant de laisser tomber les bras en &#233;tat de relaxation r&#233;cup&#233;rative normale. <\/p>\n<p align=\"justify\">2) On r&#233;alise le m&#234;me exercice, mais cette fois les mains tendues ; avant d&#8217;expulser l&#8217;air, les mains se fl&#233;chissent plusieurs fois en &#233;ventail. <\/p>\n<p align=\"justify\">3) M&#234;me exercice que le pr&#233;c&#233;dent, mais les mains ferm&#233;es. <\/p>\n<p align=\"justify\">Relaxation r&#233;cup&#233;rative debout identique &#224; celle d&#233;j&#224; d&#233;crite. <\/p>\n<p align=\"justify\">\n    <strong>Exercices abdominaux<\/strong>\n  <\/p>\n<p align=\"justify\">On inspire le maximum d&#8217;air par le nez en faisant saillir le plus possible l&#8217;abdomen. On expire ensuite lentement, en rentrant le ventre au maximum, comme si l&#8217;on voulait s&#8217;efforcer de toucher la colonne vert&#233;brale avec le nombril. On r&#233;p&#232;te cet exercice trois fois de suite. <\/p>\n<p align=\"justify\">On r&#233;p&#232;te le m&#234;me exercice, mais en augmentant progressivement la vitesse de respiration et en faisant bouger synchroniquement les parois abdominales. On le r&#233;alise le corps l&#233;g&#232;rement inclin&#233; vers l&#8217;avant, puis vers l&#8217;arri&#232;re. Cet exercice doit &#234;tre arr&#234;t&#233; &#224; la moindre g&#234;ne, &#224; la moindre sensation douloureuse dans la r&#233;gion r&#233;nale. Relaxation r&#233;cup&#233;rative debout identique &#224; celle d&#233;j&#224; d&#233;crite. <\/p>\n<p align=\"justify\">\n    <strong>Exercice &#171; NAULI &#187; <\/strong>\n  <\/p>\n<p align=\"center\">\n    <img decoding=\"async\" style=\"border-top-color: ; border-left-color: ; border-bottom-color: ; border-right-color: \" border=\"0\" hspace=\"5\" alt=\"\" vspace=\"5\" src=\"\/all_uploads\/uploads-dec17\/martie\/26.03\/15313\/15313_3.jpg\" \/>&#160;<\/p>\n<p align=\"justify\">Jambes &#233;cart&#233;es, buste l&#233;g&#232;rement en avant, mains appuy&#233;es. Sur les cuisses, on effectue la respiration abdominale d&#233;j&#224; d&#233;crite et, au moment o&#249; les parois abdominales sont profond&#233;ment contract&#233;es, l&#8217;expulsion de l&#8217;air termin&#233;e, on essaie de mobiliser les muscles abdominaux. Cet exercice sera r&#233;p&#233;t&#233; trois fois. Relaxation r&#233;cup&#233;rative debout identique &#224; celle d&#233;j&#224; d&#233;crite. <\/p>\n<p align=\"justify\">\n    <strong>Exercice de torsion <\/strong>\n  <\/p>\n<p align=\"justify\">1) Les bras lev&#233;s &#224; la verticale, les paumes des mains vers le haut, on entrecroise les doigts et on fait basculer lentement le corps &#224; droite et &#224; gauche, la respiration &#233;tant libre, l&#8217;&#233;tat de conscience profond ; le directeur de groupe rappelant de temps en temps l&#8217;objet de la m&#233;ditation. <\/p>\n<p align=\"justify\">2) On imprime une rotation axiale &#224; la moiti&#233; sup&#233;rieure du corps les bras tendus en avant et les articulations molles, le sujet tournant comme s&#8217;il voulait regarder un objet qui se trouverait derri&#232;re lui. <\/p>\n<p align=\"justify\">\n    <strong>Exercice des jambes<\/strong>\n  <\/p>\n<p align=\"justify\">Sauter sur la pointe des pieds, le corps relax&#233; au maximum &#171; en polichinelle &#187;. La respiration libre, la conscience &#233;tant &#171; au bord du sommeil &#187;. On s&#8217;arr&#234;tera au moindre malaise, &#224; la moindre g&#234;ne. <\/p>\n<p align=\"justify\">\n    <strong>Grande relaxation en d&#233;cubitus<\/strong>\n  <\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"center\">\n    <img decoding=\"async\" style=\"border-top-color: ; border-left-color: ; border-bottom-color: ; border-right-color: \" border=\"0\" hspace=\"5\" alt=\"\" vspace=\"5\" src=\"\/all_uploads\/uploads-dec17\/martie\/26.03\/15313\/15313_3.jpg\" \/>&#160;<\/p>\n<p align=\"justify\">\n    <strong><br \/>\n    <\/strong>\n  <\/p>\n<p align=\"justify\">l) En position dorsale libre, le sujet s&#8217;abandonne compl&#232;tement &#224; la sensation de r&#233;cup&#233;ration en maintenant le niveau de conscience au bord du sommeil ; l&#8217;on proc&#232;de &#224; nouveau &#224; la concentration et &#224; la m&#233;ditation, le sujet pouvant parfois atteindre la contemplation. <\/p>\n<p align=\"justify\">Rappelons que la contemplation est un ph&#233;nom&#232;ne psychologique caract&#233;ris&#233; par le fait que l&#8217;objet sur lequel on m&#233;dite persiste de lui-m&#234;me ind&#233;pendamment de tout effort de volont&#233;. L&#8217;exercice de relaxation dynamique entra&#238;ne le patient &#224; la concentration et &#224; la m&#233;ditation ; la contemplation &#233;tant un degr&#233; sup&#233;rieur permettant &#224; celui qui l&#8217;obtient d&#8217;atteindre des niveaux sup&#233;rieurs de conscience. <\/p>\n<p align=\"justify\">2) Relaxation en d&#233;cubitus lat&#233;ral droit, les jambes l&#233;g&#232;rement fl&#233;chies ; l&#8217;avant-bras droit fl&#233;chi soutient la t&#234;te et le bras gauche repose le long du corps. <\/p>\n<p align=\"justify\">3) Relaxation en d&#233;cubitus lat&#233;ral gauche, les jambes l&#233;g&#232;rement fl&#233;chies ; l&#8217;avant-bras gauche fl&#233;chi soutient la t&#234;te et le bras gauche repose le long du corps. <\/p>\n<p align=\"justify\">4) D&#233;cubitus dorsal avec r&#233;cup&#233;ration lente et tr&#232;s progressive de l&#8217;&#233;tat psychophysique ordinaire. <\/p>\n<p align=\"justify\">Fin de la p&#233;riode d&#8217;initiation en groupe et commencement de la p&#233;riode libre. <\/p>\n<p align=\"justify\">\n    <strong>III &#8211; Le Deuxi&#232;me Degr&#233; de la Relaxation Dynamique<\/strong>\n  <\/p>\n<p align=\"justify\">Le premier degr&#233; de la relaxation dynamique de Caycedo a &#233;t&#233; &#233;difi&#233; gr&#226;ce &#224; des mat&#233;riaux puis&#233;s aux sources les plus pures du YOGA hindou, l&#8217;auteur nous faisant directement exp&#233;rimenter l&#8217;ouverture de notre propre univers int&#233;rieur, ainsi que l&#8217;a not&#233; Alfredo Isasi. Dans cette premi&#232;re partie, il utilise les m&#233;canismes neurophysiologiques de l&#8217;activation du tonus musculaire et de la perception directe de la sensation de r&#233;cup&#233;ration comme moyen d&#8217;action sur la conscience. Il y ajoute ensuite l&#8217;exercice mental de la technique de m&#233;ditation pure, DHYANA, mise &#224; la port&#233;e de l&#8217;occidental et s&#8217;effectuant en &#233;tat sophronique avec ses trois temps fondamentaux : concentration, m&#233;ditation, contemplation. <\/p>\n<p align=\"justify\">Dans le deuxi&#232;me degr&#233;, Caycedo va encore plus loin, car sa nature essentiellement psychologique met &#224; notre port&#233;e certaines techniques bouddhistes recueillies notamment au Tibet. Le deuxi&#232;me degr&#233; comprend &#233;galement deux parties qui durent deux semaines chacune. <\/p>\n<p align=\"justify\">\n    <strong>Premi&#232;re partie (premi&#232;re et deuxi&#232;me semaines)<\/strong>\n  <\/p>\n<p align=\"justify\">La premi&#232;re partie dure deux semaines pendant lesquelles, journellement ou &#224; raison de trois s&#233;ances par semaine, les participants proc&#232;dent &#224; une s&#233;rie de mouvements lents se combinant avec des exercices respiratoires qui leur permettent l&#8217;exp&#233;rience directe de l&#8217;int&#233;gration de leur sch&#233;ma corporel sur les plans de la conscience. Le sophrologue directeur du groupe commence les s&#233;ances par une sophronisation collective. Par l&#8217;emploi du terpnos-logos, il sugg&#232;re une descente progressive du niveau de conscience au bord du sommeil, les participants ayant leurs yeux ferm&#233;s. La premi&#232;re sophronisation se fait, les patients se trouvant devant, puis, les yeux toujours ferm&#233;s, ils prennent place sur leurs chaises, en position assise, non pas en position du cocher, comme dans la relaxation de Schultz, mais la colonne vert&#233;brale verticale. Le sophrologue reprend la technique de m&#233;ditation DHYANA qui a d&#233;j&#224; &#233;t&#233; apprise au cours du premier degr&#233; de la relaxation dynamique et sugg&#232;re alors la m&#233;ditation sur l&#8217;objet de la concentration. Imm&#233;diatement apr&#232;s, il sugg&#232;re, dans la m&#233;ditation, la substitution &#224; l&#8217;objet du sujet lui-m&#234;me. Pour cela, il faut remplacer mentalement l&#8217;objet de la concentration par sa propre personne, par son propre corps, le patient s&#8217;imaginant envelopp&#233; par sa propre conscience. Arriv&#233; &#224; ce stade, le directeur de groupe sugg&#232;re alors la perception de l&#8217;attraction de la terre sur le corps. <\/p>\n<p align=\"justify\">Caycedo pr&#233;f&#232;re utiliser, plut&#244;t que les classiques suggestions de poids, de pesanteur corporelle, l&#8217;exp&#233;rience d&#8217;une sensation nouvelle : loi de la gravitation ressentie comme une exp&#233;rience v&#233;cue. Le terpnos-logos est utilis&#233; pour d&#233;clencher cette perception profonde par le sujet (dans l&#8217;hypnotisme classique on a toujours insist&#233; sur la sensation de pesanteur corporelle en allant m&#234;me jusqu&#8217;&#224; sugg&#233;rer au sujet qu&#8217;il lui &#233;tait impossible de bouger ses bras ou ses jambes. Caycedo reprend ce ph&#233;nom&#232;ne et s&#8217;en sert dans sa r&#233;alit&#233; la plus absolue. Pour la conscience, la sensation de l&#8217;attraction de la terre sur notre corps est r&#233;ellement une nouveaut&#233; et devient une exp&#233;rience directement v&#233;cue). <\/p>\n<p align=\"justify\">Ensuite, le sophrologue utilisera la respiration combin&#233;e avec les mouvements corporels en trois temps : <\/p>\n<p align=\"justify\">1) inspiration pendant laquelle on r&#233;alise un exercice de tension ; <\/p>\n<p align=\"justify\">2) r&#233;tention pendant quelques secondes au cours de laquelle la partie du corps mise en tension le demeure ; <\/p>\n<p>  3) expiration qui se r&#233;alise lentement tandis que la partie du corps qui a &#233;t&#233; mise sous tension revient &#224; sa position initiale. <\/p>\n<p>&#160;<br \/>\n  Lisez la <a href=\"\/moved_content.php?lang=FR&amp;item=15367\" target=\"_blank\" rel=\"noopener\">quatrieme partie<\/a> de cet article<\/p>\n<p><strong>yogaesoteric<\/strong><\/p>\n<p>    <strong>26 mars 2018<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lisez la&#160;deuxi&#232;me partie de cet article&#160; Exercice respiratoire n&#176; 4 &#160; Cet exercice se d&#233;roule en trois temps : l) On tend le bras droit en avant, on inspire par la bouche en fermant le poing et, tout en retenant l&#8217;air, on effectue quelques rotations avec le bras, puis on expulse l&#8217;air fortement par le [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uf_show_specific_survey":0,"_uf_disable_surveys":false,"footnotes":""},"categories":[707],"tags":[],"class_list":["post-25011","post","type-post","status-publish","format-standard","hentry","category-tehnici-yoga-simple-1587-ro"],"_links":{"self":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/25011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/comments?post=25011"}],"version-history":[{"count":0,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/posts\/25011\/revisions"}],"wp:attachment":[{"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/media?parent=25011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/categories?post=25011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yogaesoteric.net\/fr\/wp-json\/wp\/v2\/tags?post=25011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}